{"id":5362,"date":"2020-12-14T16:40:30","date_gmt":"2020-12-14T15:40:30","guid":{"rendered":"https:\/\/dieter-jenz.de\/lc\/?page_id=5362"},"modified":"2023-03-07T08:28:10","modified_gmt":"2023-03-07T07:28:10","slug":"zitate-quelle-jaures-jean","status":"publish","type":"page","link":"https:\/\/dieter-jenz.de\/lc\/zitate-nach-quellen\/zitate-quelle-jaures-jean\/","title":{"rendered":"Jaures, Jean"},"content":{"rendered":"<div class=\"pt-cv-wrapper\"><div class=\"pt-cv-view pt-cv-grid pt-cv-colsys\" id=\"pt-cv-view-ad52e355j1\"><div data-id=\"pt-cv-page-1\" class=\"pt-cv-page\" data-cvc=\"4\"><div class=\"col-md-3 col-sm-6 col-xs-12 pt-cv-content-item pt-cv-1-col\" ><div class='pt-cv-ifield'><a href=\"https:\/\/dieter-jenz.de\/lc\/die-groessten-menschen-sind-jene-die-anderen-hoffnung-jaures\/\" class=\"_self pt-cv-href-thumbnail pt-cv-thumb-default\" target=\"_self\" ><img loading=\"lazy\" decoding=\"async\" width=\"200\" height=\"300\" src=\"https:\/\/dieter-jenz.de\/lc\/wp-content\/uploads\/2020\/01\/Die-gr\u00f6\u00dften-Menschen-sind-jene-J.-Jaures-200x300.jpeg\" class=\"pt-cv-thumbnail\" alt=\"Die gr\u00f6\u00dften Menschen sind jene, J. Jaures - Gestaltung: privat\" srcset=\"https:\/\/dieter-jenz.de\/lc\/wp-content\/uploads\/2020\/01\/Die-gr\u00f6\u00dften-Menschen-sind-jene-J.-Jaures-200x300.jpeg 200w, https:\/\/dieter-jenz.de\/lc\/wp-content\/uploads\/2020\/01\/Die-gr\u00f6\u00dften-Menschen-sind-jene-J.-Jaures-683x1024.jpeg 683w, https:\/\/dieter-jenz.de\/lc\/wp-content\/uploads\/2020\/01\/Die-gr\u00f6\u00dften-Menschen-sind-jene-J.-Jaures-540x810.jpeg 540w, https:\/\/dieter-jenz.de\/lc\/wp-content\/uploads\/2020\/01\/Die-gr\u00f6\u00dften-Menschen-sind-jene-J.-Jaures-100x150.jpeg 100w, https:\/\/dieter-jenz.de\/lc\/wp-content\/uploads\/2020\/01\/Die-gr\u00f6\u00dften-Menschen-sind-jene-J.-Jaures.jpeg 735w\" sizes=\"(max-width: 200px) 100vw, 200px\" \/><\/a><\/div><\/div><\/div><\/div><\/div>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":2,"featured_media":0,"parent":5164,"menu_order":450,"comment_status":"closed","ping_status":"closed","template":"template-full-width-only-content.php","meta":{"footnotes":""},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Jaures, Jean<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dieter-jenz.de\/lc\/zitate-nach-quellen\/zitate-quelle-jaures-jean\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Jaures, Jean\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dieter-jenz.de\/lc\/zitate-nach-quellen\/zitate-quelle-jaures-jean\/\" \/>\n<meta property=\"og:site_name\" content=\"Dieter Jenz, Begleitung und Coaching\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/dieter.jenz.inspiration\" \/>\n<meta property=\"article:modified_time\" content=\"2023-03-07T07:28:10+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@dieterjenz\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/dieter-jenz.de\/lc\/zitate-nach-quellen\/zitate-quelle-jaures-jean\/\",\"url\":\"https:\/\/dieter-jenz.de\/lc\/zitate-nach-quellen\/zitate-quelle-jaures-jean\/\",\"name\":\"Jaures, Jean\",\"isPartOf\":{\"@id\":\"https:\/\/dieter-jenz.de\/lc\/#website\"},\"datePublished\":\"2020-12-14T15:40:30+00:00\",\"dateModified\":\"2023-03-07T07:28:10+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/dieter-jenz.de\/lc\/zitate-nach-quellen\/zitate-quelle-jaures-jean\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/dieter-jenz.de\/lc\/zitate-nach-quellen\/zitate-quelle-jaures-jean\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/dieter-jenz.de\/lc\/zitate-nach-quellen\/zitate-quelle-jaures-jean\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/dieter-jenz.de\/lc\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Zitate nach Quellen, alphabetisch\",\"item\":\"https:\/\/dieter-jenz.de\/lc\/zitate-nach-quellen\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Jaures, Jean\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/dieter-jenz.de\/lc\/#website\",\"url\":\"https:\/\/dieter-jenz.de\/lc\/\",\"name\":\"Dieter Jenz, Begleitung und Coaching\",\"description\":\"Die andere, neue Sichtweise entdecken - auftanken - neue Wege gehen\",\"publisher\":{\"@id\":\"https:\/\/dieter-jenz.de\/lc\/#\/schema\/person\/618cfd5c289d0a23930cb258a43679ab\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/dieter-jenz.de\/lc\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\/\/dieter-jenz.de\/lc\/#\/schema\/person\/618cfd5c289d0a23930cb258a43679ab\",\"name\":\"Dieter Jenz\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/dieter-jenz.de\/lc\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/dieter-jenz.de\/lc\/wp-content\/uploads\/2020\/01\/Logo-Coaching-und-Begleitung.png\",\"contentUrl\":\"https:\/\/dieter-jenz.de\/lc\/wp-content\/uploads\/2020\/01\/Logo-Coaching-und-Begleitung.png\",\"width\":320,\"height\":240,\"caption\":\"Dieter Jenz\"},\"logo\":{\"@id\":\"https:\/\/dieter-jenz.de\/lc\/#\/schema\/person\/image\/\"},\"description\":\"Ich bin Dieter Jenz, Begleiter, Berater und Coach mit Leidenschaft. \u00dcber viele Jahre hinweg habe ich einen reichen Schatz an Kompetenz und Erfahrung erworben. Meine Themen sind die \\\"4L\\\": Lebensaufgabe, Lebensplanung, Lebensnavigation und Lebensqualit\u00e4t.\",\"sameAs\":[\"https:\/\/www.facebook.com\/dieter.jenz.inspiration\",\"https:\/\/www.pinterest.de\/dieterjenz\/\",\"https:\/\/x.com\/https:\/\/twitter.com\/dieterjenz\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Jaures, Jean","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dieter-jenz.de\/lc\/zitate-nach-quellen\/zitate-quelle-jaures-jean\/","og_locale":"de_DE","og_type":"article","og_title":"Jaures, Jean","og_url":"https:\/\/dieter-jenz.de\/lc\/zitate-nach-quellen\/zitate-quelle-jaures-jean\/","og_site_name":"Dieter Jenz, Begleitung und Coaching","article_publisher":"https:\/\/www.facebook.com\/dieter.jenz.inspiration","article_modified_time":"2023-03-07T07:28:10+00:00","twitter_card":"summary_large_image","twitter_site":"@dieterjenz","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/dieter-jenz.de\/lc\/zitate-nach-quellen\/zitate-quelle-jaures-jean\/","url":"https:\/\/dieter-jenz.de\/lc\/zitate-nach-quellen\/zitate-quelle-jaures-jean\/","name":"Jaures, Jean","isPartOf":{"@id":"https:\/\/dieter-jenz.de\/lc\/#website"},"datePublished":"2020-12-14T15:40:30+00:00","dateModified":"2023-03-07T07:28:10+00:00","breadcrumb":{"@id":"https:\/\/dieter-jenz.de\/lc\/zitate-nach-quellen\/zitate-quelle-jaures-jean\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dieter-jenz.de\/lc\/zitate-nach-quellen\/zitate-quelle-jaures-jean\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/dieter-jenz.de\/lc\/zitate-nach-quellen\/zitate-quelle-jaures-jean\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/dieter-jenz.de\/lc\/"},{"@type":"ListItem","position":2,"name":"Zitate nach Quellen, alphabetisch","item":"https:\/\/dieter-jenz.de\/lc\/zitate-nach-quellen\/"},{"@type":"ListItem","position":3,"name":"Jaures, Jean"}]},{"@type":"WebSite","@id":"https:\/\/dieter-jenz.de\/lc\/#website","url":"https:\/\/dieter-jenz.de\/lc\/","name":"Dieter Jenz, Begleitung und Coaching","description":"Die andere, neue Sichtweise entdecken - auftanken - neue Wege gehen","publisher":{"@id":"https:\/\/dieter-jenz.de\/lc\/#\/schema\/person\/618cfd5c289d0a23930cb258a43679ab"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dieter-jenz.de\/lc\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":["Person","Organization"],"@id":"https:\/\/dieter-jenz.de\/lc\/#\/schema\/person\/618cfd5c289d0a23930cb258a43679ab","name":"Dieter Jenz","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/dieter-jenz.de\/lc\/#\/schema\/person\/image\/","url":"https:\/\/dieter-jenz.de\/lc\/wp-content\/uploads\/2020\/01\/Logo-Coaching-und-Begleitung.png","contentUrl":"https:\/\/dieter-jenz.de\/lc\/wp-content\/uploads\/2020\/01\/Logo-Coaching-und-Begleitung.png","width":320,"height":240,"caption":"Dieter Jenz"},"logo":{"@id":"https:\/\/dieter-jenz.de\/lc\/#\/schema\/person\/image\/"},"description":"Ich bin Dieter Jenz, Begleiter, Berater und Coach mit Leidenschaft. \u00dcber viele Jahre hinweg habe ich einen reichen Schatz an Kompetenz und Erfahrung erworben. Meine Themen sind die \"4L\": Lebensaufgabe, Lebensplanung, Lebensnavigation und Lebensqualit\u00e4t.","sameAs":["https:\/\/www.facebook.com\/dieter.jenz.inspiration","https:\/\/www.pinterest.de\/dieterjenz\/","https:\/\/x.com\/https:\/\/twitter.com\/dieterjenz"]}]}},"_links":{"self":[{"href":"https:\/\/dieter-jenz.de\/lc\/wp-json\/wp\/v2\/pages\/5362"}],"collection":[{"href":"https:\/\/dieter-jenz.de\/lc\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/dieter-jenz.de\/lc\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/dieter-jenz.de\/lc\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/dieter-jenz.de\/lc\/wp-json\/wp\/v2\/comments?post=5362"}],"version-history":[{"count":3,"href":"https:\/\/dieter-jenz.de\/lc\/wp-json\/wp\/v2\/pages\/5362\/revisions"}],"predecessor-version":[{"id":8431,"href":"https:\/\/dieter-jenz.de\/lc\/wp-json\/wp\/v2\/pages\/5362\/revisions\/8431"}],"up":[{"embeddable":true,"href":"https:\/\/dieter-jenz.de\/lc\/wp-json\/wp\/v2\/pages\/5164"}],"wp:attachment":[{"href":"https:\/\/dieter-jenz.de\/lc\/wp-json\/wp\/v2\/media?parent=5362"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}