{"id":2564,"date":"2019-11-06T09:54:15","date_gmt":"2019-11-06T07:54:15","guid":{"rendered":"https:\/\/dieter-jenz.de\/lc\/?p=2564"},"modified":"2021-03-18T10:36:36","modified_gmt":"2021-03-18T09:36:36","slug":"10-inspirierende-zitate-von-dietrich-bonhoeffer","status":"publish","type":"post","link":"https:\/\/dieter-jenz.de\/lc\/10-inspirierende-zitate-von-dietrich-bonhoeffer\/","title":{"rendered":"Inspirierende Zitate von Dietrich Bonhoeffer &#8211; nachdenkenswert"},"content":{"rendered":"\n<p>Inspirierende Zitate von Dietrich Bonhoeffer.<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter is-resized\"><a href=\"https:\/\/dieter-jenz.de\/lc\/wp-content\/uploads\/2019\/11\/10-Zitate-Dietrich-Bonhoeffer.jpeg\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/dieter-jenz.de\/lc\/wp-content\/uploads\/2019\/11\/10-Zitate-Dietrich-Bonhoeffer-200x300.jpeg\" alt=\"10 inspirierende Zitate von Dietrich Bonhoeffer - Bildquelle: Bundesarchiv_Bild_146-1987-074-16, Gestaltung: privat\" class=\"wp-image-2562\" width=\"300\" height=\"450\" srcset=\"https:\/\/dieter-jenz.de\/lc\/wp-content\/uploads\/2019\/11\/10-Zitate-Dietrich-Bonhoeffer-200x300.jpeg 200w, https:\/\/dieter-jenz.de\/lc\/wp-content\/uploads\/2019\/11\/10-Zitate-Dietrich-Bonhoeffer-683x1024.jpeg 683w, https:\/\/dieter-jenz.de\/lc\/wp-content\/uploads\/2019\/11\/10-Zitate-Dietrich-Bonhoeffer-100x150.jpeg 100w, https:\/\/dieter-jenz.de\/lc\/wp-content\/uploads\/2019\/11\/10-Zitate-Dietrich-Bonhoeffer.jpeg 735w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a><figcaption>Bildquelle: Bundesarchiv Bild 146-1987-074-16, Gestaltung: privat<\/figcaption><\/figure><\/div>\n\n\n\n<p>Dietrich Bonhoeffer (1906-1945) war ein deutscher Theologe, profilierter Vertreter der Bekennenden Kirche, einer Oppositionsbewegung evangelischer Christen, und am Widerstand gegen den Nationalsozialismus beteiligt.<\/p>\n\n\n\n<!--more-->\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Die eigene \u00dcberzeugung konsequent gelebt<\/strong><\/h3>\n\n\n\n<p>Dietrich Bonhoeffer war einer der pr\u00e4genden Menschen im Widerstand gegen das NS-Regime. Als Theologe war Gott f\u00fcr ihn keine Fiktion, sondern Realit\u00e4t, die seinem Leben Ausrichtung gab.<\/p>\n\n\n\n<p>Mit dem Namen Dietrich Bonhoeffer verbindet sich gelebtes Christsein, politischer Widerstand und Zivilcourage. Seine gelebte \u00dcberzeugung brachte ihn ins Gef\u00e4ngnis und schlie\u00dflich in das Konzentrationslager Flossenb\u00fcrg. Dort wurde er nur wenige Wochen vor Kriegsende hingerichtet.<\/p>\n\n\n\n<p>Dietrich Bonhoeffer warnte schon sehr fr\u00fch vor den Gefahren der am 30. Januar 1933 mit Adolf Hitler als Reichskanzler gebildeten neuen Regierung. In einer schon zwei Tage nach der Regierungs\u00fcbernahme in Berlin gehaltenen Rundfunkrede sprach er davon, dass der \u201eF\u00fchrer\u201c zum \u201eVerf\u00fchrer\u201c werden k\u00f6nne. Die Rede wurde abrupt abgebrochen.<\/p>\n\n\n\n<p>Auch in seiner eigenen Kirche, der evangelischen Kirche, stie\u00df Dietrich Bonhoeffer auf Widerstand. Er war Mitautor eines Glaubensbekenntnisses, das strikt gegen die Deutschen Christen (eine rassistische, antisemitische und am F\u00fchrerprinzip orientierte Str\u00f6mung im deutschen Protestantismus) und gegen die vom NS-Regime installierte Deutsche Reichskirche gerichtet war. Jedoch fand er wenig Unterst\u00fctzung.<\/p>\n\n\n\n<p>Der staatliche Arierparagraph, der die Grundlage f\u00fcr den Ausschluss getaufter Juden als \u201eNichtarier\u201c aus der Evangelischen Kirche bildete, war Anlass f\u00fcr die Gr\u00fcndung des Pfarrernotbunds im September 1933. Zu den Gr\u00fcndern z\u00e4hlte auch Dietrich Bonhoeffer. &nbsp;Der Pfarrernotbund war ein Vorl\u00e4ufer der 1934 gegr\u00fcndeten Bekennenden Kirche, der Dietrich Bonhoeffer ebenfalls angeh\u00f6rte.<\/p>\n\n\n\n<p>Dietrich Bonhoeffers Entscheidung, sich von Beginn an in Opposition zum NS-Regime zu begeben, hatte f\u00fcr ihn wegweisenden Charakter. Er blieb seinen \u00dcberzeugungen treu, wohl getragen von der Hoffnung, dass er direkt oder indirekt ein fr\u00fcheres Ende des Regimes herbeif\u00fchren k\u00f6nnte.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Ein reichhaltiger Nachlass<\/h3>\n\n\n\n<p>Von Dietrich Bonhoeffer sind theologische Schriften, Briefe und B\u00fccher erhalten geblieben. Fast alle heute bekannten Zitate wurden daraus entnommen. Die Gott-Mensch-Beziehung, zwischenmenschliche Beziehungen, Dankbarkeit, Vertrauen, Liebe und Freude sind die wichtigsten Schwerpunktthemen.<\/p>\n\n\n\n<p>Von Authentizit\u00e4t gepr\u00e4gte, inspirierende Zitate von Dietrich Bonhoeffer spiegeln sein Leben und Wirken wider. Sie geben Einblick in seine Werte und \u00dcberzeugungen in einer schwierigen Zeit.<\/p>\n\n\n\n<p><em>Mit einem Klick auf ein Bild oder durch Antippen eines Bildes (bei ber\u00fchrungsempfindlichen Displays) gelangen Sie zum zugeh\u00f6rigen Text.<\/em><\/p>\n\n\n<div class=\"pt-cv-wrapper\"><div class=\"pt-cv-view pt-cv-grid pt-cv-colsys\" id=\"pt-cv-view-69e34adg8z\"><div data-id=\"pt-cv-page-1\" class=\"pt-cv-page\" data-cvc=\"4\"><div class=\"col-md-3 col-sm-6 col-xs-12 pt-cv-content-item pt-cv-1-col\" ><div class='pt-cv-ifield'><a href=\"https:\/\/dieter-jenz.de\/lc\/in-der-dankbarkeit-gewinne-ich-bonhoeffer\/\" class=\"_self pt-cv-href-thumbnail pt-cv-thumb-default\" target=\"_self\" ><img loading=\"lazy\" decoding=\"async\" width=\"200\" height=\"300\" src=\"https:\/\/dieter-jenz.de\/lc\/wp-content\/uploads\/2019\/11\/In-der-Dankbarkeit-gewinne-ich-D.-Bonhoeffer-200x300.jpeg\" class=\"pt-cv-thumbnail\" alt=\"In der Dankbarkeit gewinne ich, D. Bonhoeffer - Gestaltung: privat\" srcset=\"https:\/\/dieter-jenz.de\/lc\/wp-content\/uploads\/2019\/11\/In-der-Dankbarkeit-gewinne-ich-D.-Bonhoeffer-200x300.jpeg 200w, https:\/\/dieter-jenz.de\/lc\/wp-content\/uploads\/2019\/11\/In-der-Dankbarkeit-gewinne-ich-D.-Bonhoeffer-683x1024.jpeg 683w, https:\/\/dieter-jenz.de\/lc\/wp-content\/uploads\/2019\/11\/In-der-Dankbarkeit-gewinne-ich-D.-Bonhoeffer-100x150.jpeg 100w, https:\/\/dieter-jenz.de\/lc\/wp-content\/uploads\/2019\/11\/In-der-Dankbarkeit-gewinne-ich-D.-Bonhoeffer.jpeg 735w\" sizes=\"(max-width: 200px) 100vw, 200px\" \/><\/a><\/div><\/div>\n<div class=\"col-md-3 col-sm-6 col-xs-12 pt-cv-content-item pt-cv-1-col\" ><div class='pt-cv-ifield'><a href=\"https:\/\/dieter-jenz.de\/lc\/jedes-werden-in-der-natur-bonhoeffer\/\" class=\"_self pt-cv-href-thumbnail pt-cv-thumb-default\" target=\"_self\" ><img loading=\"lazy\" decoding=\"async\" width=\"200\" height=\"300\" src=\"https:\/\/dieter-jenz.de\/lc\/wp-content\/uploads\/2019\/11\/Jedes-Werden-in-der-Natur-D.-Bonhoeffer-200x300.jpeg\" class=\"pt-cv-thumbnail\" alt=\"Jedes Werden in der Natur, D. Bonhoeffer - Gestaltung: privat\" srcset=\"https:\/\/dieter-jenz.de\/lc\/wp-content\/uploads\/2019\/11\/Jedes-Werden-in-der-Natur-D.-Bonhoeffer-200x300.jpeg 200w, https:\/\/dieter-jenz.de\/lc\/wp-content\/uploads\/2019\/11\/Jedes-Werden-in-der-Natur-D.-Bonhoeffer-683x1024.jpeg 683w, https:\/\/dieter-jenz.de\/lc\/wp-content\/uploads\/2019\/11\/Jedes-Werden-in-der-Natur-D.-Bonhoeffer-100x150.jpeg 100w, https:\/\/dieter-jenz.de\/lc\/wp-content\/uploads\/2019\/11\/Jedes-Werden-in-der-Natur-D.-Bonhoeffer.jpeg 735w\" sizes=\"(max-width: 200px) 100vw, 200px\" \/><\/a><\/div><\/div>\n<div class=\"col-md-3 col-sm-6 col-xs-12 pt-cv-content-item pt-cv-1-col\" ><div class='pt-cv-ifield'><a href=\"https:\/\/dieter-jenz.de\/lc\/im-normalen-leben-wird-einem-oft-gar-nicht-bewusst-bonhoeffer\/\" class=\"_self pt-cv-href-thumbnail pt-cv-thumb-default\" target=\"_self\" ><img loading=\"lazy\" decoding=\"async\" width=\"200\" height=\"300\" src=\"https:\/\/dieter-jenz.de\/lc\/wp-content\/uploads\/2019\/11\/Im-normalen-Leben-wird-einem-D.-Bonhoeffer-200x300.jpeg\" class=\"pt-cv-thumbnail\" alt=\"Im normalen Leben wird einem, D. Bonhoeffer - Gestaltung: privat\" srcset=\"https:\/\/dieter-jenz.de\/lc\/wp-content\/uploads\/2019\/11\/Im-normalen-Leben-wird-einem-D.-Bonhoeffer-200x300.jpeg 200w, https:\/\/dieter-jenz.de\/lc\/wp-content\/uploads\/2019\/11\/Im-normalen-Leben-wird-einem-D.-Bonhoeffer-683x1024.jpeg 683w, https:\/\/dieter-jenz.de\/lc\/wp-content\/uploads\/2019\/11\/Im-normalen-Leben-wird-einem-D.-Bonhoeffer-100x150.jpeg 100w, https:\/\/dieter-jenz.de\/lc\/wp-content\/uploads\/2019\/11\/Im-normalen-Leben-wird-einem-D.-Bonhoeffer.jpeg 735w\" sizes=\"(max-width: 200px) 100vw, 200px\" \/><\/a><\/div><\/div>\n<div class=\"col-md-3 col-sm-6 col-xs-12 pt-cv-content-item pt-cv-1-col\" ><div class='pt-cv-ifield'><a href=\"https:\/\/dieter-jenz.de\/lc\/die-liebe-will-nichts-von-dem-anderen-bonhoeffer\/\" class=\"_self pt-cv-href-thumbnail pt-cv-thumb-default\" target=\"_self\" ><img loading=\"lazy\" decoding=\"async\" width=\"200\" height=\"300\" src=\"https:\/\/dieter-jenz.de\/lc\/wp-content\/uploads\/2019\/11\/Die-Liebe-will-nichts-D.-Bonhoeffer-200x300.jpeg\" class=\"pt-cv-thumbnail\" alt=\"Die Liebe will nichts, D. Bonhoeffer - Gestaltung: privat\" srcset=\"https:\/\/dieter-jenz.de\/lc\/wp-content\/uploads\/2019\/11\/Die-Liebe-will-nichts-D.-Bonhoeffer-200x300.jpeg 200w, https:\/\/dieter-jenz.de\/lc\/wp-content\/uploads\/2019\/11\/Die-Liebe-will-nichts-D.-Bonhoeffer-683x1024.jpeg 683w, https:\/\/dieter-jenz.de\/lc\/wp-content\/uploads\/2019\/11\/Die-Liebe-will-nichts-D.-Bonhoeffer-100x150.jpeg 100w, https:\/\/dieter-jenz.de\/lc\/wp-content\/uploads\/2019\/11\/Die-Liebe-will-nichts-D.-Bonhoeffer.jpeg 735w\" sizes=\"(max-width: 200px) 100vw, 200px\" \/><\/a><\/div><\/div><\/div><\/div>\n<div class=\" pt-cv-pagination-wrapper\"><ul class=\"pt-cv-pagination pt-cv-ajax pagination\" data-totalpages=\"3\" data-currentpage=\"1\" data-sid=\"69e34adg8z\" data-unid=\"\" data-isblock=\"\" data-postid=\"\"><li class=\"active\"><a href=\"#\">1<\/a><\/li>\n\t<li ><a class=\"\" href=\"https:\/\/dieter-jenz.de\/lc\/wp-json\/wp\/v2\/posts\/2564\/?_page=2\">2<\/a><\/li>\n\t<li ><a class=\"\" href=\"https:\/\/dieter-jenz.de\/lc\/wp-json\/wp\/v2\/posts\/2564\/?_page=3\">3<\/a><\/li>\n\t<li ><a class=\" \" href=\"https:\/\/dieter-jenz.de\/lc\/wp-json\/wp\/v2\/posts\/2564\/?_page=2\">&rsaquo;<\/a><\/li>\n\t<\/ul><img loading=\"lazy\" decoding=\"async\" width=\"15\" height=\"15\" class=\"pt-cv-spinner\" alt=\"Wird geladen\u00a0\u2026\" src=\"data:image\/gif;base64,R0lGODlhDwAPALMPAMrKygwMDJOTkz09PZWVla+vr3p6euTk5M7OzuXl5TMzMwAAAJmZmWZmZszMzP\/\/\/yH\/C05FVFNDQVBFMi4wAwEAAAAh+QQFCgAPACwAAAAADwAPAAAEQvDJaZaZOIcV8iQK8VRX4iTYoAwZ4iCYoAjZ4RxejhVNoT+mRGP4cyF4Pp0N98sBGIBMEMOotl6YZ3S61Bmbkm4mAgAh+QQFCgAPACwAAAAADQANAAAENPDJSRSZeA418itN8QiK8BiLITVsFiyBBIoYqnoewAD4xPw9iY4XLGYSjkQR4UAUD45DLwIAIfkEBQoADwAsAAAAAA8ACQAABC\/wyVlamTi3nSdgwFNdhEJgTJoNyoB9ISYoQmdjiZPcj7EYCAeCF1gEDo4Dz2eIAAAh+QQFCgAPACwCAAAADQANAAAEM\/DJBxiYeLKdX3IJZT1FU0iIg2RNKx3OkZVnZ98ToRD4MyiDnkAh6BkNC0MvsAj0kMpHBAAh+QQFCgAPACwGAAAACQAPAAAEMDC59KpFDll73HkAA2wVY5KgiK5b0RRoI6MuzG6EQqCDMlSGheEhUAgqgUUAFRySIgAh+QQFCgAPACwCAAIADQANAAAEM\/DJKZNLND\/kkKaHc3xk+QAMYDKsiaqmZCxGVjSFFCxB1vwy2oOgIDxuucxAMTAJFAJNBAAh+QQFCgAPACwAAAYADwAJAAAEMNAs86q1yaWwwv2Ig0jUZx3OYa4XoRAfwADXoAwfo1+CIjyFRuEho60aSNYlOPxEAAAh+QQFCgAPACwAAAIADQANAAAENPA9s4y8+IUVcqaWJ4qEQozSoAzoIyhCK2NFU2SJk0hNnyEOhKR2AzAAj4Pj4GE4W0bkJQIAOw==\" \/><div class=\"clear pt-cv-clear-pagination\"><\/div><\/div><\/div>\n\n\n<div class=\"su-box su-box-style-default\" id=\"\" style=\"border-color:#000000;border-radius:3px;\"><div class=\"su-box-title\" style=\"background-color:#333333;color:#FFFFFF;border-top-left-radius:1px;border-top-right-radius:1px\">Aktuelles<\/div><div class=\"su-box-content su-u-clearfix su-u-trim\" style=\"border-bottom-left-radius:1px;border-bottom-right-radius:1px\"><ul id=\"menu-post-menue\" class=\"menu\"><li id=\"menu-item-4536\" class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-home menu-item-4536\"><a href=\"https:\/\/dieter-jenz.de\/lc\/\">Home<\/a><\/li>\n<li id=\"menu-item-5989\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-5989\"><a href=\"https:\/\/dieter-jenz.de\/lc\/zitate-zum-nachdenken-und-neudenken-uebersicht\/\">Alle Zitate &#8211; \u00dcbersicht<\/a><\/li>\n<li id=\"menu-item-4537\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-4537\"><a href=\"https:\/\/dieter-jenz.de\/lc\/zitate-hitlisten\/\">Zitate-Hitlisten \u2013 Beliebte Zitate<\/a><\/li>\n<li id=\"menu-item-5011\" class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-5011\"><a href=\"https:\/\/dieter-jenz.de\/lc\/?redirect_to=random&#038;cat=68\">\u00dcberraschungs-Zitat<\/a><\/li>\n<li id=\"menu-item-4565\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-4565\"><a href=\"https:\/\/dieter-jenz.de\/lc\/neueste-beitraege\/\">Neueste Beitr\u00e4ge<\/a><\/li>\n<li id=\"menu-item-5925\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-5925\"><a href=\"https:\/\/dieter-jenz.de\/lc\/zitate-kuerzlich-ueberarbeitet\/\">K\u00fcrzlich \u00fcberarbeitet<\/a><\/li>\n<li id=\"menu-item-5836\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-5836\"><a href=\"https:\/\/dieter-jenz.de\/lc\/impulse-zur-inspiration-und-motivation-in-sozialen-medien-dieter-jenz\/\">Links zu sozialen Medien<\/a><\/li>\n<\/ul><\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Inspirierende Zitate von Dietrich Bonhoeffer. Dietrich Bonhoeffer (1906-1945) war ein deutscher Theologe, profilierter Vertreter der Bekennenden Kirche, einer Oppositionsbewegung evangelischer Christen, und am Widerstand gegen den Nationalsozialismus beteiligt.<\/p>\n","protected":false},"author":2,"featured_media":2562,"comment_status":"closed","ping_status":"open","sticky":false,"template":"template-full-width-only-content.php","format":"standard","meta":{"footnotes":""},"categories":[119,64,115],"tags":[65],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Inspirierende Zitate von Dietrich Bonhoeffer - nachdenkenswert<\/title>\n<meta name=\"description\" content=\"Inspirierende Zitate von Dietrich Bonhoeffer, deutscher Theologe, im Widerstand gegen das NS-Regime, Mitglied der Bekennenden Kirche.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dieter-jenz.de\/lc\/10-inspirierende-zitate-von-dietrich-bonhoeffer\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Inspirierende Zitate von Dietrich Bonhoeffer - nachdenkenswert\" \/>\n<meta property=\"og:description\" content=\"Inspirierende Zitate von Dietrich Bonhoeffer, deutscher Theologe, im Widerstand gegen das NS-Regime, Mitglied der Bekennenden Kirche.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dieter-jenz.de\/lc\/10-inspirierende-zitate-von-dietrich-bonhoeffer\/\" \/>\n<meta property=\"og:site_name\" content=\"Dieter Jenz, Begleitung und Coaching\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/dieter.jenz.inspiration\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/dieter.jenz.inspiration\" \/>\n<meta property=\"article:published_time\" content=\"2019-11-06T07:54:15+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-03-18T09:36:36+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dieter-jenz.de\/lc\/wp-content\/uploads\/2019\/11\/10-Zitate-Dietrich-Bonhoeffer.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"735\" \/>\n\t<meta property=\"og:image:height\" content=\"1102\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Dieter Jenz\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/dieterjenz\" \/>\n<meta name=\"twitter:site\" content=\"@dieterjenz\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Dieter Jenz\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"2\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/dieter-jenz.de\/lc\/10-inspirierende-zitate-von-dietrich-bonhoeffer\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/dieter-jenz.de\/lc\/10-inspirierende-zitate-von-dietrich-bonhoeffer\/\"},\"author\":{\"name\":\"Dieter Jenz\",\"@id\":\"https:\/\/dieter-jenz.de\/lc\/#\/schema\/person\/618cfd5c289d0a23930cb258a43679ab\"},\"headline\":\"Inspirierende Zitate von Dietrich Bonhoeffer &#8211; nachdenkenswert\",\"datePublished\":\"2019-11-06T07:54:15+00:00\",\"dateModified\":\"2021-03-18T09:36:36+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/dieter-jenz.de\/lc\/10-inspirierende-zitate-von-dietrich-bonhoeffer\/\"},\"wordCount\":392,\"publisher\":{\"@id\":\"https:\/\/dieter-jenz.de\/lc\/#\/schema\/person\/618cfd5c289d0a23930cb258a43679ab\"},\"image\":{\"@id\":\"https:\/\/dieter-jenz.de\/lc\/10-inspirierende-zitate-von-dietrich-bonhoeffer\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dieter-jenz.de\/lc\/wp-content\/uploads\/2019\/11\/10-Zitate-Dietrich-Bonhoeffer.jpeg\",\"keywords\":[\"Inspiration\"],\"articleSection\":[\"Bonhoeffer, Dietrich\",\"Ermutigung und Inspiration\",\"Zitatesammlungen (Personen)\"],\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/dieter-jenz.de\/lc\/10-inspirierende-zitate-von-dietrich-bonhoeffer\/\",\"url\":\"https:\/\/dieter-jenz.de\/lc\/10-inspirierende-zitate-von-dietrich-bonhoeffer\/\",\"name\":\"Inspirierende Zitate von Dietrich Bonhoeffer - nachdenkenswert\",\"isPartOf\":{\"@id\":\"https:\/\/dieter-jenz.de\/lc\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/dieter-jenz.de\/lc\/10-inspirierende-zitate-von-dietrich-bonhoeffer\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/dieter-jenz.de\/lc\/10-inspirierende-zitate-von-dietrich-bonhoeffer\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dieter-jenz.de\/lc\/wp-content\/uploads\/2019\/11\/10-Zitate-Dietrich-Bonhoeffer.jpeg\",\"datePublished\":\"2019-11-06T07:54:15+00:00\",\"dateModified\":\"2021-03-18T09:36:36+00:00\",\"description\":\"Inspirierende Zitate von Dietrich Bonhoeffer, deutscher Theologe, im Widerstand gegen das NS-Regime, Mitglied der Bekennenden Kirche.\",\"breadcrumb\":{\"@id\":\"https:\/\/dieter-jenz.de\/lc\/10-inspirierende-zitate-von-dietrich-bonhoeffer\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/dieter-jenz.de\/lc\/10-inspirierende-zitate-von-dietrich-bonhoeffer\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/dieter-jenz.de\/lc\/10-inspirierende-zitate-von-dietrich-bonhoeffer\/#primaryimage\",\"url\":\"https:\/\/dieter-jenz.de\/lc\/wp-content\/uploads\/2019\/11\/10-Zitate-Dietrich-Bonhoeffer.jpeg\",\"contentUrl\":\"https:\/\/dieter-jenz.de\/lc\/wp-content\/uploads\/2019\/11\/10-Zitate-Dietrich-Bonhoeffer.jpeg\",\"width\":735,\"height\":1102,\"caption\":\"10 inspirierende Zitate von Dietrich Bonhoeffer - Bildquelle: Bundesarchiv_Bild_146-1987-074-16, Gestaltung: privat\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/dieter-jenz.de\/lc\/10-inspirierende-zitate-von-dietrich-bonhoeffer\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/dieter-jenz.de\/lc\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Ermutigung und Inspiration\",\"item\":\"https:\/\/dieter-jenz.de\/lc\/category\/ermutigung-und-inspiration\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Inspirierende Zitate von Dietrich Bonhoeffer &#8211; nachdenkenswert\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/dieter-jenz.de\/lc\/#website\",\"url\":\"https:\/\/dieter-jenz.de\/lc\/\",\"name\":\"Dieter Jenz, Begleitung und Coaching\",\"description\":\"Die andere, neue Sichtweise entdecken - auftanken - neue Wege gehen\",\"publisher\":{\"@id\":\"https:\/\/dieter-jenz.de\/lc\/#\/schema\/person\/618cfd5c289d0a23930cb258a43679ab\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/dieter-jenz.de\/lc\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\/\/dieter-jenz.de\/lc\/#\/schema\/person\/618cfd5c289d0a23930cb258a43679ab\",\"name\":\"Dieter Jenz\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/dieter-jenz.de\/lc\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/dieter-jenz.de\/lc\/wp-content\/uploads\/2020\/01\/Logo-Coaching-und-Begleitung.png\",\"contentUrl\":\"https:\/\/dieter-jenz.de\/lc\/wp-content\/uploads\/2020\/01\/Logo-Coaching-und-Begleitung.png\",\"width\":320,\"height\":240,\"caption\":\"Dieter Jenz\"},\"logo\":{\"@id\":\"https:\/\/dieter-jenz.de\/lc\/#\/schema\/person\/image\/\"},\"description\":\"Ich bin Dieter Jenz, Begleiter, Berater und Coach mit Leidenschaft. \u00dcber viele Jahre hinweg habe ich einen reichen Schatz an Kompetenz und Erfahrung erworben. Meine Themen sind die \\\"4L\\\": Lebensaufgabe, Lebensplanung, Lebensnavigation und Lebensqualit\u00e4t.\",\"sameAs\":[\"https:\/\/www.facebook.com\/dieter.jenz.inspiration\",\"https:\/\/www.pinterest.de\/dieterjenz\/\",\"https:\/\/x.com\/https:\/\/twitter.com\/dieterjenz\"],\"url\":\"https:\/\/dieter-jenz.de\/lc\/author\/dieter\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Inspirierende Zitate von Dietrich Bonhoeffer - nachdenkenswert","description":"Inspirierende Zitate von Dietrich Bonhoeffer, deutscher Theologe, im Widerstand gegen das NS-Regime, Mitglied der Bekennenden Kirche.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dieter-jenz.de\/lc\/10-inspirierende-zitate-von-dietrich-bonhoeffer\/","og_locale":"de_DE","og_type":"article","og_title":"Inspirierende Zitate von Dietrich Bonhoeffer - nachdenkenswert","og_description":"Inspirierende Zitate von Dietrich Bonhoeffer, deutscher Theologe, im Widerstand gegen das NS-Regime, Mitglied der Bekennenden Kirche.","og_url":"https:\/\/dieter-jenz.de\/lc\/10-inspirierende-zitate-von-dietrich-bonhoeffer\/","og_site_name":"Dieter Jenz, Begleitung und Coaching","article_publisher":"https:\/\/www.facebook.com\/dieter.jenz.inspiration","article_author":"https:\/\/www.facebook.com\/dieter.jenz.inspiration","article_published_time":"2019-11-06T07:54:15+00:00","article_modified_time":"2021-03-18T09:36:36+00:00","og_image":[{"width":735,"height":1102,"url":"https:\/\/dieter-jenz.de\/lc\/wp-content\/uploads\/2019\/11\/10-Zitate-Dietrich-Bonhoeffer.jpeg","type":"image\/jpeg"}],"author":"Dieter Jenz","twitter_card":"summary_large_image","twitter_creator":"@https:\/\/twitter.com\/dieterjenz","twitter_site":"@dieterjenz","twitter_misc":{"Verfasst von":"Dieter Jenz","Gesch\u00e4tzte Lesezeit":"2\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/dieter-jenz.de\/lc\/10-inspirierende-zitate-von-dietrich-bonhoeffer\/#article","isPartOf":{"@id":"https:\/\/dieter-jenz.de\/lc\/10-inspirierende-zitate-von-dietrich-bonhoeffer\/"},"author":{"name":"Dieter Jenz","@id":"https:\/\/dieter-jenz.de\/lc\/#\/schema\/person\/618cfd5c289d0a23930cb258a43679ab"},"headline":"Inspirierende Zitate von Dietrich Bonhoeffer &#8211; nachdenkenswert","datePublished":"2019-11-06T07:54:15+00:00","dateModified":"2021-03-18T09:36:36+00:00","mainEntityOfPage":{"@id":"https:\/\/dieter-jenz.de\/lc\/10-inspirierende-zitate-von-dietrich-bonhoeffer\/"},"wordCount":392,"publisher":{"@id":"https:\/\/dieter-jenz.de\/lc\/#\/schema\/person\/618cfd5c289d0a23930cb258a43679ab"},"image":{"@id":"https:\/\/dieter-jenz.de\/lc\/10-inspirierende-zitate-von-dietrich-bonhoeffer\/#primaryimage"},"thumbnailUrl":"https:\/\/dieter-jenz.de\/lc\/wp-content\/uploads\/2019\/11\/10-Zitate-Dietrich-Bonhoeffer.jpeg","keywords":["Inspiration"],"articleSection":["Bonhoeffer, Dietrich","Ermutigung und Inspiration","Zitatesammlungen (Personen)"],"inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/dieter-jenz.de\/lc\/10-inspirierende-zitate-von-dietrich-bonhoeffer\/","url":"https:\/\/dieter-jenz.de\/lc\/10-inspirierende-zitate-von-dietrich-bonhoeffer\/","name":"Inspirierende Zitate von Dietrich Bonhoeffer - nachdenkenswert","isPartOf":{"@id":"https:\/\/dieter-jenz.de\/lc\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dieter-jenz.de\/lc\/10-inspirierende-zitate-von-dietrich-bonhoeffer\/#primaryimage"},"image":{"@id":"https:\/\/dieter-jenz.de\/lc\/10-inspirierende-zitate-von-dietrich-bonhoeffer\/#primaryimage"},"thumbnailUrl":"https:\/\/dieter-jenz.de\/lc\/wp-content\/uploads\/2019\/11\/10-Zitate-Dietrich-Bonhoeffer.jpeg","datePublished":"2019-11-06T07:54:15+00:00","dateModified":"2021-03-18T09:36:36+00:00","description":"Inspirierende Zitate von Dietrich Bonhoeffer, deutscher Theologe, im Widerstand gegen das NS-Regime, Mitglied der Bekennenden Kirche.","breadcrumb":{"@id":"https:\/\/dieter-jenz.de\/lc\/10-inspirierende-zitate-von-dietrich-bonhoeffer\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dieter-jenz.de\/lc\/10-inspirierende-zitate-von-dietrich-bonhoeffer\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/dieter-jenz.de\/lc\/10-inspirierende-zitate-von-dietrich-bonhoeffer\/#primaryimage","url":"https:\/\/dieter-jenz.de\/lc\/wp-content\/uploads\/2019\/11\/10-Zitate-Dietrich-Bonhoeffer.jpeg","contentUrl":"https:\/\/dieter-jenz.de\/lc\/wp-content\/uploads\/2019\/11\/10-Zitate-Dietrich-Bonhoeffer.jpeg","width":735,"height":1102,"caption":"10 inspirierende Zitate von Dietrich Bonhoeffer - Bildquelle: Bundesarchiv_Bild_146-1987-074-16, Gestaltung: privat"},{"@type":"BreadcrumbList","@id":"https:\/\/dieter-jenz.de\/lc\/10-inspirierende-zitate-von-dietrich-bonhoeffer\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/dieter-jenz.de\/lc\/"},{"@type":"ListItem","position":2,"name":"Ermutigung und Inspiration","item":"https:\/\/dieter-jenz.de\/lc\/category\/ermutigung-und-inspiration\/"},{"@type":"ListItem","position":3,"name":"Inspirierende Zitate von Dietrich Bonhoeffer &#8211; nachdenkenswert"}]},{"@type":"WebSite","@id":"https:\/\/dieter-jenz.de\/lc\/#website","url":"https:\/\/dieter-jenz.de\/lc\/","name":"Dieter Jenz, Begleitung und Coaching","description":"Die andere, neue Sichtweise entdecken - auftanken - neue Wege gehen","publisher":{"@id":"https:\/\/dieter-jenz.de\/lc\/#\/schema\/person\/618cfd5c289d0a23930cb258a43679ab"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dieter-jenz.de\/lc\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":["Person","Organization"],"@id":"https:\/\/dieter-jenz.de\/lc\/#\/schema\/person\/618cfd5c289d0a23930cb258a43679ab","name":"Dieter Jenz","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/dieter-jenz.de\/lc\/#\/schema\/person\/image\/","url":"https:\/\/dieter-jenz.de\/lc\/wp-content\/uploads\/2020\/01\/Logo-Coaching-und-Begleitung.png","contentUrl":"https:\/\/dieter-jenz.de\/lc\/wp-content\/uploads\/2020\/01\/Logo-Coaching-und-Begleitung.png","width":320,"height":240,"caption":"Dieter Jenz"},"logo":{"@id":"https:\/\/dieter-jenz.de\/lc\/#\/schema\/person\/image\/"},"description":"Ich bin Dieter Jenz, Begleiter, Berater und Coach mit Leidenschaft. \u00dcber viele Jahre hinweg habe ich einen reichen Schatz an Kompetenz und Erfahrung erworben. Meine Themen sind die \"4L\": Lebensaufgabe, Lebensplanung, Lebensnavigation und Lebensqualit\u00e4t.","sameAs":["https:\/\/www.facebook.com\/dieter.jenz.inspiration","https:\/\/www.pinterest.de\/dieterjenz\/","https:\/\/x.com\/https:\/\/twitter.com\/dieterjenz"],"url":"https:\/\/dieter-jenz.de\/lc\/author\/dieter\/"}]}},"_links":{"self":[{"href":"https:\/\/dieter-jenz.de\/lc\/wp-json\/wp\/v2\/posts\/2564"}],"collection":[{"href":"https:\/\/dieter-jenz.de\/lc\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dieter-jenz.de\/lc\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dieter-jenz.de\/lc\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/dieter-jenz.de\/lc\/wp-json\/wp\/v2\/comments?post=2564"}],"version-history":[{"count":4,"href":"https:\/\/dieter-jenz.de\/lc\/wp-json\/wp\/v2\/posts\/2564\/revisions"}],"predecessor-version":[{"id":6018,"href":"https:\/\/dieter-jenz.de\/lc\/wp-json\/wp\/v2\/posts\/2564\/revisions\/6018"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dieter-jenz.de\/lc\/wp-json\/wp\/v2\/media\/2562"}],"wp:attachment":[{"href":"https:\/\/dieter-jenz.de\/lc\/wp-json\/wp\/v2\/media?parent=2564"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dieter-jenz.de\/lc\/wp-json\/wp\/v2\/categories?post=2564"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dieter-jenz.de\/lc\/wp-json\/wp\/v2\/tags?post=2564"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}