							<style type="text/css" media="screen">
							#is-ajax-search-result-4451 .is-highlight { background-color: #FFFFB9 !important;}
							#is-ajax-search-result-4451 .meta .is-highlight { background-color: transparent !important;}
							</style>
						{"id":4082,"date":"2020-08-11T08:00:00","date_gmt":"2020-08-11T06:00:00","guid":{"rendered":"https:\/\/dieter-jenz.de\/lc\/?p=4082"},"modified":"2024-01-31T09:32:30","modified_gmt":"2024-01-31T08:32:30","slug":"freundschaft-waehrt-am-laengsten-wenn-sie-mit-dem-versprechen-besiegelt-wird-emerson","status":"publish","type":"post","link":"https:\/\/dieter-jenz.de\/lc\/freundschaft-waehrt-am-laengsten-wenn-sie-mit-dem-versprechen-besiegelt-wird-emerson\/","title":{"rendered":"Freundschaft w\u00e4hrt am l\u00e4ngsten, wenn sie mit &#8230; besiegelt wird"},"content":{"rendered":"<div class=\"yoast-breadcrumbs\"><span><span><a href=\"https:\/\/dieter-jenz.de\/lc\/\">Home<\/a><\/span> \u00bb <span><a href=\"https:\/\/dieter-jenz.de\/lc\/category\/ermutigung-und-inspiration\/\">Ermutigung und Inspiration<\/a><\/span> \u00bb <span class=\"breadcrumb_last\" aria-current=\"page\"><strong>Freundschaft w\u00e4hrt am l\u00e4ngsten, wenn sie mit &#8230; besiegelt wird<\/strong><\/span><\/span><\/div>\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p>\u201eFreundschaft w\u00e4hrt am l\u00e4ngsten, wenn sie mit dem gegenseitigen Versprechen, sich immer die Wahrheit zu sagen, besiegelt wird.\u201c <\/p>\n<cite>Ralph Waldo Emerson<\/cite><\/blockquote>\n\n\n<div class=\"wp-block-image is-resized\">\n<figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"683\" height=\"1024\" src=\"https:\/\/dieter-jenz.de\/lc\/wp-content\/uploads\/2020\/08\/Freundschaft-w\u00e4hrt-am-l\u00e4ngsten-R.W.-Emerson-683x1024.jpeg\" alt=\"Freundschaft w\u00e4hrt am l\u00e4ngsten, wenn sie mit dem gegenseitigen Versprechen ... besiegelt wird, R.W. Emerson - Gestaltung: privat\" class=\"wp-image-4081\" style=\"object-fit:cover;width:300px;height:450px\" srcset=\"https:\/\/dieter-jenz.de\/lc\/wp-content\/uploads\/2020\/08\/Freundschaft-w\u00e4hrt-am-l\u00e4ngsten-R.W.-Emerson-683x1024.jpeg 683w, https:\/\/dieter-jenz.de\/lc\/wp-content\/uploads\/2020\/08\/Freundschaft-w\u00e4hrt-am-l\u00e4ngsten-R.W.-Emerson-200x300.jpeg 200w, https:\/\/dieter-jenz.de\/lc\/wp-content\/uploads\/2020\/08\/Freundschaft-w\u00e4hrt-am-l\u00e4ngsten-R.W.-Emerson-540x810.jpeg 540w, https:\/\/dieter-jenz.de\/lc\/wp-content\/uploads\/2020\/08\/Freundschaft-w\u00e4hrt-am-l\u00e4ngsten-R.W.-Emerson-100x150.jpeg 100w, https:\/\/dieter-jenz.de\/lc\/wp-content\/uploads\/2020\/08\/Freundschaft-w\u00e4hrt-am-l\u00e4ngsten-R.W.-Emerson.jpeg 735w\" sizes=\"(max-width: 683px) 100vw, 683px\" \/><figcaption class=\"wp-element-caption\">Gestaltung: privat<\/figcaption><\/figure><\/div>\n\n\n<p>Ralph Waldo Emerson (1803-1882), war ein US-amerikanischer Philosoph und Schriftsteller. Er engagierte sich f\u00fcr soziale Reformen, wie beispielsweise das Frauenwahlrecht. Au\u00dferdem sprach er sich gegen die Sklaverei aus.<\/p>\n\n\n\n<!--more-->\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Muss man in einer Freundschaft alles \u00fcber sich preisgeben?<\/strong><\/h3>\n\n\n\n<p>Stefan (*) und Christoph (*) sind schon seit mehreren Jahren miteinander befreundet. Die Freundschaft wurde nie &#8222;offiziell&#8220; besiegelt, sondern entwickelte sich \u00fcber die Zeit. Die beiden haben gegenseitiges Vertrauen zueinander aufgebaut. Sie wissen viel voneinander, und vielleicht wissen einiges davon ihre jeweiligen Ehefrauen nicht.<\/p>\n\n\n\n<p>Obwohl Stefan im Lauf der Zeit schon viel von sich preisgegeben hat, so hat er doch \u00fcber ein sehr unangenehmes Kapitel seines Lebens geschwiegen. Er hat es vor seinem Freund verborgen. Es w\u00e4re ihm peinlich, darauf zu sprechen zu kommen, denn auf sein damaliges Verhalten und Handeln war er alles andere als stolz. Sollte er das Thema von sich aus irgendwann doch einmal bei passender Gelegenheit ansprechen?<\/p>\n\n\n<div class=\"su-box su-box-style-default\" id=\"\" style=\"border-color:#000000;border-radius:3px;\"><div class=\"su-box-title\" style=\"background-color:#333333;color:#FFFFFF;border-top-left-radius:1px;border-top-right-radius:1px\">Aktuelles<\/div><div class=\"su-box-content su-u-clearfix su-u-trim\" style=\"border-bottom-left-radius:1px;border-bottom-right-radius:1px\"><ul id=\"menu-post-menue\" class=\"menu\"><li id=\"menu-item-4536\" class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-home menu-item-4536\"><a href=\"https:\/\/dieter-jenz.de\/lc\/\">Home<\/a><\/li>\n<li id=\"menu-item-5989\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-5989\"><a href=\"https:\/\/dieter-jenz.de\/lc\/zitate-zum-nachdenken-und-neudenken-uebersicht\/\">Alle Zitate &#8211; \u00dcbersicht<\/a><\/li>\n<li id=\"menu-item-4537\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-4537\"><a href=\"https:\/\/dieter-jenz.de\/lc\/zitate-hitlisten\/\">Zitate-Hitlisten \u2013 Beliebte Zitate<\/a><\/li>\n<li id=\"menu-item-5011\" class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-5011\"><a href=\"https:\/\/dieter-jenz.de\/lc\/?redirect_to=random&#038;cat=68\">\u00dcberraschungs-Zitat<\/a><\/li>\n<li id=\"menu-item-4565\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-4565\"><a href=\"https:\/\/dieter-jenz.de\/lc\/neueste-beitraege\/\">Neueste Beitr\u00e4ge<\/a><\/li>\n<li id=\"menu-item-5925\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-5925\"><a href=\"https:\/\/dieter-jenz.de\/lc\/zitate-kuerzlich-ueberarbeitet\/\">K\u00fcrzlich \u00fcberarbeitet<\/a><\/li>\n<li id=\"menu-item-5836\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-5836\"><a href=\"https:\/\/dieter-jenz.de\/lc\/impulse-zur-inspiration-und-motivation-in-sozialen-medien-dieter-jenz\/\">Links zu sozialen Medien<\/a><\/li>\n<\/ul><\/div><\/div>\n\n\n\n<p>Die Frage f\u00fcr Stefan ist, ob es die Freundschaft betrifft und ob es f\u00fcr die Freundschaft mit Christoph wichtig ist. Stefan ist \u00fcberzeugt, dass dieses Thema in der Beziehung mit Christoph und f\u00fcr ihre Freundschaft keinerlei Bedeutung hat. Ihre Freundschaft w\u00fcrde weder bereichert noch beeintr\u00e4chtigt werden, wenn er dar\u00fcber spr\u00e4che.<\/p>\n\n\n\n<p>F\u00fcr Stefan ist dieses unangenehme und dunkle Kapitel seines Lebens abgeschlossen. Es ist nichts mehr zu kl\u00e4ren. Und eine Meinung seines Freundes zu dem einen oder anderen Aspekt w\u00fcnscht er sich derzeit nicht. Also beschlie\u00dft er, es beim Status Quo zu belassen.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Einander immer die Wahrheit sagen?<\/strong><\/h3>\n\n\n\n<p>Was w\u00e4re, wenn Christoph eines Tages zuf\u00e4llig auf dieses Kapitel in Stefans Leben zu sprechen kommen w\u00fcrde? Vielleicht etwa so: \u201eDa war doch mal was mit \u2026 Wie ist das eigentlich weiter gegangen?&#8220;.<\/p>\n\n\n\n<p>Stefan st\u00fcnde vor der Frage, wie er darauf reagieren will. Er k\u00f6nnte Christoph sagen, dass er dar\u00fcber nicht reden m\u00f6chte. Das w\u00fcrde zwar Christophs Neugier reizen, aber dieser w\u00fcrde Stefans Wunsch respektieren, nicht dar\u00fcber sprechen zu wollen.<\/p>\n\n\n\n<p>Wenn sich Stefan daf\u00fcr entscheidet, dar\u00fcber zu sprechen, ist nur seine subjektive Wahrheit hilfreich. Er macht sich verletzlich, wenn er Dinge ausspricht, die ihn in Christophs Augen in ein anderes Licht r\u00fccken k\u00f6nnten. Er riskiert, dass sein Freund einen anderen, nicht mehr so positiven Eindruck von ihm bekommt. Andererseits ist es f\u00fcr Christoph ein Vertrauensbeweis, wenn Stefan ihm gegen\u00fcber offen und ehrlich ist. Die Freundschaft ist dadurch besiegelt, dass Stefan auch dann bei der Wahrheit bleibt, wenn es ihm eigentlich unangenehm ist.<\/p>\n\n\n\n<div class=\"wp-block-group\"><div class=\"wp-block-group__inner-container is-layout-constrained wp-block-group-is-layout-constrained\">\n<figure class=\"wp-block-gallery has-nested-images columns-4 is-cropped wp-block-gallery-2 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/dieter-jenz.de\/lc\/portal-lebensweisheiten\/\" target=\"_blank\" rel=\"noreferrer noopener\"><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"800\" data-id=\"10179\" src=\"https:\/\/dieter-jenz.de\/lc\/wp-content\/uploads\/2023\/12\/Lebensweisheiten.jpeg\" alt=\"Lebensweisheiten - Gestaltung: privat\" class=\"wp-image-10179\" srcset=\"https:\/\/dieter-jenz.de\/lc\/wp-content\/uploads\/2023\/12\/Lebensweisheiten.jpeg 800w, https:\/\/dieter-jenz.de\/lc\/wp-content\/uploads\/2023\/12\/Lebensweisheiten-300x300.jpeg 300w, https:\/\/dieter-jenz.de\/lc\/wp-content\/uploads\/2023\/12\/Lebensweisheiten-150x150.jpeg 150w, https:\/\/dieter-jenz.de\/lc\/wp-content\/uploads\/2023\/12\/Lebensweisheiten-768x768.jpeg 768w, https:\/\/dieter-jenz.de\/lc\/wp-content\/uploads\/2023\/12\/Lebensweisheiten-540x540.jpeg 540w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/a><figcaption class=\"wp-element-caption\">Gestaltung: privat<\/figcaption><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/dieter-jenz.de\/lc\/portal-evergreen-themen\/\" target=\"_blank\" rel=\"noreferrer noopener\"><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"800\" data-id=\"10200\" src=\"https:\/\/dieter-jenz.de\/lc\/wp-content\/uploads\/2023\/12\/Evergreen-Themen.jpeg\" alt=\"Evergreen-Themen - Gestaltung: privat\" class=\"wp-image-10200\" srcset=\"https:\/\/dieter-jenz.de\/lc\/wp-content\/uploads\/2023\/12\/Evergreen-Themen.jpeg 800w, https:\/\/dieter-jenz.de\/lc\/wp-content\/uploads\/2023\/12\/Evergreen-Themen-300x300.jpeg 300w, https:\/\/dieter-jenz.de\/lc\/wp-content\/uploads\/2023\/12\/Evergreen-Themen-150x150.jpeg 150w, https:\/\/dieter-jenz.de\/lc\/wp-content\/uploads\/2023\/12\/Evergreen-Themen-768x768.jpeg 768w, https:\/\/dieter-jenz.de\/lc\/wp-content\/uploads\/2023\/12\/Evergreen-Themen-540x540.jpeg 540w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/a><figcaption class=\"wp-element-caption\">Gestaltung: privat<\/figcaption><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/dieter-jenz.de\/lc\/portal-wissensdurst\/\" target=\"_blank\" rel=\"noreferrer noopener\"><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"800\" data-id=\"10177\" src=\"https:\/\/dieter-jenz.de\/lc\/wp-content\/uploads\/2023\/12\/Wissensdurst-Blick-durch-den-Tuerspalt.jpeg\" alt=\"Wissensdurst, Blick durch den T\u00fcrspalt - Gestaltung: privat\" class=\"wp-image-10177\" srcset=\"https:\/\/dieter-jenz.de\/lc\/wp-content\/uploads\/2023\/12\/Wissensdurst-Blick-durch-den-Tuerspalt.jpeg 800w, https:\/\/dieter-jenz.de\/lc\/wp-content\/uploads\/2023\/12\/Wissensdurst-Blick-durch-den-Tuerspalt-300x300.jpeg 300w, https:\/\/dieter-jenz.de\/lc\/wp-content\/uploads\/2023\/12\/Wissensdurst-Blick-durch-den-Tuerspalt-150x150.jpeg 150w, https:\/\/dieter-jenz.de\/lc\/wp-content\/uploads\/2023\/12\/Wissensdurst-Blick-durch-den-Tuerspalt-768x768.jpeg 768w, https:\/\/dieter-jenz.de\/lc\/wp-content\/uploads\/2023\/12\/Wissensdurst-Blick-durch-den-Tuerspalt-540x540.jpeg 540w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/a><figcaption class=\"wp-element-caption\">Gestaltung: privat<\/figcaption><\/figure>\n<\/figure>\n<\/div><\/div>\n\n\n\n<p>Stefan hat nicht zu bef\u00fcrchten, dass die Freundschaft besch\u00e4digt wird, denn sie k\u00f6nnen beide auf eine solide Vertrauensbasis bauen. Er wei\u00df, dass Christoph das Gesagte vertraulich behandeln wird. Und weil Christoph sich seiner eigenen Schattenseiten bewusst ist, hat er auch Nachsicht mit Stefan.<\/p>\n\n\n\n<p>Schlimm w\u00e4re es, wenn Stefan zwar dar\u00fcber sprechen, aber nicht die Wahrheit sagen w\u00fcrde. Stefan w\u00fcrde sich selbst eine Last auflegen. Er m\u00fcsste sich genau merken, was er Christoph gesagt hat, damit er sich sp\u00e4ter nicht widerspricht, sollte das Thema irgendwann einmal wieder darauf kommen. Zum anderen w\u00e4re es durch einen ungl\u00fccklichen Zufall vielleicht m\u00f6glich, dass Christoph aus anderer Quelle etwas erf\u00e4hrt. Dann stellt er entt\u00e4uscht fest, dass Stefan ihm die Unwahrheit gesagt hat. Und dann w\u00e4re die Freundschaft tats\u00e4chlich besch\u00e4digt. Sie h\u00e4tte eine schwere Schramme bekommen, weil Vertrauen verloren ging.<\/p>\n\n\n\n<p>Die Freundschaft lie\u00dfe sich retten, denn eine Freundschaft lebt auch vom Verzeihen, je l\u00e4nger sie andauert. Johann Wolfgang von Goethe dr\u00fcckte es so aus: \u201e<a href=\"https:\/\/dieter-jenz.de\/lc\/aeltere-freundschaften-haben-vor-neuen-hauptsaechlich-voraus-goethe\/\">\u00c4ltere Freundschaften haben vor neuen haupts\u00e4chlich voraus, dass man sich schon viel verziehen hat.<\/a>\u201c. Aber die Schramme w\u00e4re unn\u00f6tig gewesen.<\/p>\n\n\n\n<p>* Name(n) ge\u00e4ndert<\/p>\n\n\n<div class=\"su-box su-box-style-default\" id=\"\" style=\"border-color:#000000;border-radius:3px;\"><div class=\"su-box-title\" style=\"background-color:#333333;color:#FFFFFF;border-top-left-radius:1px;border-top-right-radius:1px\">Zitate nach Quellen <\/div><div class=\"su-box-content su-u-clearfix su-u-trim\" style=\"border-bottom-left-radius:1px;border-bottom-right-radius:1px\"><div class=\"su-expand su-expand-collapsed su-expand-link-style-default\" data-height=\"100\"><div class=\"su-expand-content su-u-trim\" style=\"color:#333333;max-height:100px;overflow:hidden\"><ul class=\"su-subpages\"><li class=\"page_item page-item-5533\"><a href=\"https:\/\/dieter-jenz.de\/lc\/zitate-nach-quellen\/zitate-quelle-adler-alfred\/\">Adler, Alfred<\/a><\/li>\n<li class=\"page_item page-item-5530\"><a href=\"https:\/\/dieter-jenz.de\/lc\/zitate-nach-quellen\/zitate-quelle-aichinger-ilse\/\">Aichinger, Ilse<\/a><\/li>\n<li class=\"page_item page-item-5527\"><a href=\"https:\/\/dieter-jenz.de\/lc\/zitate-nach-quellen\/zitate-quelle-allert-wybranietz-kristiane\/\">Allert-Wybranietz, Kristiane<\/a><\/li>\n<li class=\"page_item page-item-6624\"><a href=\"https:\/\/dieter-jenz.de\/lc\/zitate-nach-quellen\/zitate-quelle-angelou-maya\/\">Angelou, Maya<\/a><\/li>\n<li class=\"page_item page-item-5524\"><a href=\"https:\/\/dieter-jenz.de\/lc\/zitate-nach-quellen\/zitate-quelle-arendt-hannah\/\">Arendt, Hannah<\/a><\/li>\n<li class=\"page_item page-item-5517\"><a href=\"https:\/\/dieter-jenz.de\/lc\/zitate-nach-quellen\/zitate-quelle-bauer-nicole\/\">Bauer, Nicole<\/a><\/li>\n<li class=\"page_item page-item-5514\"><a href=\"https:\/\/dieter-jenz.de\/lc\/zitate-nach-quellen\/zitate-quelle-bismarck-otto-von\/\">Bismarck, Otto von<\/a><\/li>\n<li class=\"page_item page-item-5511\"><a href=\"https:\/\/dieter-jenz.de\/lc\/zitate-nach-quellen\/zitate-quelle-bloch-ernst\/\">Bloch, Ernst<\/a><\/li>\n<li class=\"page_item page-item-5508\"><a href=\"https:\/\/dieter-jenz.de\/lc\/zitate-nach-quellen\/zitate-quelle-bodelschwingh-friedrich-von\/\">Bodelschwingh, Friedrich von<\/a><\/li>\n<li class=\"page_item page-item-5505\"><a href=\"https:\/\/dieter-jenz.de\/lc\/zitate-nach-quellen\/zitate-quelle-bonhoeffer-dietrich\/\">Bonhoeffer, Dietrich<\/a><\/li>\n<li class=\"page_item page-item-5502\"><a href=\"https:\/\/dieter-jenz.de\/lc\/zitate-nach-quellen\/zitate-quelle-buber-martin\/\">Buber, Martin<\/a><\/li>\n<li class=\"page_item page-item-5499\"><a href=\"https:\/\/dieter-jenz.de\/lc\/zitate-nach-quellen\/zitate-quelle-bucay-jorge\/\">Bucay, Jorge<\/a><\/li>\n<li class=\"page_item page-item-5490\"><a href=\"https:\/\/dieter-jenz.de\/lc\/zitate-nach-quellen\/zitate-quelle-carnegie-dale\/\">Carnegie, Dale<\/a><\/li>\n<li class=\"page_item page-item-5487\"><a href=\"https:\/\/dieter-jenz.de\/lc\/zitate-nach-quellen\/zitate-quelle-carroll-lewis\/\">Carroll, Lewis<\/a><\/li>\n<li class=\"page_item page-item-5484\"><a href=\"https:\/\/dieter-jenz.de\/lc\/zitate-nach-quellen\/zitate-quelle-ceelen-petrus\/\">Ceelen, Petrus<\/a><\/li>\n<li class=\"page_item page-item-5481\"><a href=\"https:\/\/dieter-jenz.de\/lc\/zitate-nach-quellen\/zitate-quelle-chamfort-nicolas\/\">Chamfort, Nicolas<\/a><\/li>\n<li class=\"page_item page-item-5478\"><a href=\"https:\/\/dieter-jenz.de\/lc\/zitate-nach-quellen\/zitate-quelle-churchill-winston\/\">Churchill, Winston<\/a><\/li>\n<li class=\"page_item page-item-5475\"><a href=\"https:\/\/dieter-jenz.de\/lc\/zitate-nach-quellen\/zitate-quelle-claudius-matthias\/\">Claudius, Matthias<\/a><\/li>\n<li class=\"page_item page-item-5472\"><a href=\"https:\/\/dieter-jenz.de\/lc\/zitate-nach-quellen\/zitate-quelle-coelho-paulo\/\">Coelho, Paulo<\/a><\/li>\n<li class=\"page_item page-item-5469\"><a href=\"https:\/\/dieter-jenz.de\/lc\/zitate-nach-quellen\/zitate-quelle-coue-emil\/\">Coue, Emil<\/a><\/li>\n<li class=\"page_item page-item-5456\"><a href=\"https:\/\/dieter-jenz.de\/lc\/zitate-nach-quellen\/zitate-quelle-darwin-charles\/\">Darwin, Charles<\/a><\/li>\n<li class=\"page_item page-item-5453\"><a href=\"https:\/\/dieter-jenz.de\/lc\/zitate-nach-quellen\/zitate-quelle-delp-alfred\/\">Delp, Alfred<\/a><\/li>\n<li class=\"page_item page-item-5450\"><a href=\"https:\/\/dieter-jenz.de\/lc\/zitate-nach-quellen\/zitate-quelle-dickens-charles\/\">Dickens, Charles<\/a><\/li>\n<li class=\"page_item page-item-5447\"><a href=\"https:\/\/dieter-jenz.de\/lc\/zitate-nach-quellen\/zitate-quelle-dietrich-marlene\/\">Dietrich, Marlene<\/a><\/li>\n<li class=\"page_item page-item-5440\"><a href=\"https:\/\/dieter-jenz.de\/lc\/zitate-nach-quellen\/zitate-quelle-ebner-eschenbach-marie-von\/\">Ebner-Eschenbach, Marie von<\/a><\/li>\n<li class=\"page_item page-item-5437\"><a href=\"https:\/\/dieter-jenz.de\/lc\/zitate-nach-quellen\/zitate-quelle-emerson-ralph-waldo\/\">Emerson, Ralph Waldo<\/a><\/li>\n<li class=\"page_item page-item-8897\"><a href=\"https:\/\/dieter-jenz.de\/lc\/zitate-nach-quellen\/zitate-quelle-emmons-robert\/\">Emmons, Robert<\/a><\/li>\n<li class=\"page_item page-item-5432\"><a href=\"https:\/\/dieter-jenz.de\/lc\/zitate-nach-quellen\/zitate-quelle-feuerbach-ludwig\/\">Feuerbach, Ludwig<\/a><\/li>\n<li class=\"page_item page-item-5429\"><a href=\"https:\/\/dieter-jenz.de\/lc\/zitate-nach-quellen\/zitate-quelle-firus-christian\/\">Firus, Christian<\/a><\/li>\n<li class=\"page_item page-item-5426\"><a href=\"https:\/\/dieter-jenz.de\/lc\/zitate-nach-quellen\/zitate-quelle-ford-henry\/\">Ford, Henry<\/a><\/li>\n<li class=\"page_item page-item-6020\"><a href=\"https:\/\/dieter-jenz.de\/lc\/zitate-nach-quellen\/zitate-quelle-foucauld-charles-de\/\">Foucauld, Charles de<\/a><\/li>\n<li class=\"page_item page-item-5423\"><a href=\"https:\/\/dieter-jenz.de\/lc\/zitate-nach-quellen\/zitate-quelle-frankl-viktor\/\">Frankl, Viktor<\/a><\/li>\n<li class=\"page_item page-item-5420\"><a href=\"https:\/\/dieter-jenz.de\/lc\/zitate-nach-quellen\/zitate-quelle-friedrich-der-grosse\/\">Friedrich der Grosse<\/a><\/li>\n<li class=\"page_item page-item-5417\"><a href=\"https:\/\/dieter-jenz.de\/lc\/zitate-nach-quellen\/zitate-quelle-frisch-max\/\">Frisch, Max<\/a><\/li>\n<li class=\"page_item page-item-5414\"><a href=\"https:\/\/dieter-jenz.de\/lc\/zitate-nach-quellen\/zitate-quelle-fromm-erich\/\">Fromm, Erich<\/a><\/li>\n<li class=\"page_item page-item-5406\"><a href=\"https:\/\/dieter-jenz.de\/lc\/zitate-nach-quellen\/zitate-quelle-galilei-galileo\/\">Galilei, Galileo<\/a><\/li>\n<li class=\"page_item page-item-5403\"><a href=\"https:\/\/dieter-jenz.de\/lc\/zitate-nach-quellen\/zitate-quelle-gandhi-mahatma\/\">Gandhi, Mahatma<\/a><\/li>\n<li class=\"page_item page-item-5400\"><a href=\"https:\/\/dieter-jenz.de\/lc\/zitate-nach-quellen\/zitate-quelle-gide-andre\/\">Gide, Andre<\/a><\/li>\n<li class=\"page_item page-item-5711\"><a href=\"https:\/\/dieter-jenz.de\/lc\/zitate-nach-quellen\/zitate-gleim-johann-wilhelm-ludwig\/\">Gleim, Johann Wilhelm Ludwig<\/a><\/li>\n<li class=\"page_item page-item-5397\"><a href=\"https:\/\/dieter-jenz.de\/lc\/zitate-nach-quellen\/zitate-quelle-goethe-johann-wolfgang-von\/\">Goethe, Johann Wolfgang von<\/a><\/li>\n<li class=\"page_item page-item-5394\"><a href=\"https:\/\/dieter-jenz.de\/lc\/zitate-nach-quellen\/zitate-quelle-goldman-emma\/\">Goldman, Emma<\/a><\/li>\n<li class=\"page_item page-item-5391\"><a href=\"https:\/\/dieter-jenz.de\/lc\/zitate-nach-quellen\/zitate-quelle-hanson-rick\/\">Hanson, Rick<\/a><\/li>\n<li class=\"page_item page-item-5388\"><a href=\"https:\/\/dieter-jenz.de\/lc\/zitate-nach-quellen\/zitate-quelle-havel-vaclav\/\">Havel, Vaclav<\/a><\/li>\n<li class=\"page_item page-item-5385\"><a href=\"https:\/\/dieter-jenz.de\/lc\/zitate-nach-quellen\/zitate-quelle-hesse-hermann\/\">Hesse, Hermann<\/a><\/li>\n<li class=\"page_item page-item-5382\"><a href=\"https:\/\/dieter-jenz.de\/lc\/zitate-nach-quellen\/zitate-quelle-hubbard-elbert\/\">Hubbard, Elbert<\/a><\/li>\n<li class=\"page_item page-item-5378\"><a href=\"https:\/\/dieter-jenz.de\/lc\/zitate-nach-quellen\/zitate-quelle-huether-gerald\/\">H\u00fcther, Gerald<\/a><\/li>\n<li class=\"page_item page-item-5366\"><a href=\"https:\/\/dieter-jenz.de\/lc\/zitate-nach-quellen\/zitate-quelle-jaspers-karl\/\">Jaspers, Karl<\/a><\/li>\n<li class=\"page_item page-item-5362\"><a href=\"https:\/\/dieter-jenz.de\/lc\/zitate-nach-quellen\/zitate-quelle-jaures-jean\/\">Jaures, Jean<\/a><\/li>\n<li class=\"page_item page-item-5358\"><a href=\"https:\/\/dieter-jenz.de\/lc\/zitate-nach-quellen\/zitate-quelle-jenz-dieter\/\">Jenz, Dieter<\/a><\/li>\n<li class=\"page_item page-item-5354\"><a href=\"https:\/\/dieter-jenz.de\/lc\/zitate-nach-quellen\/zitate-quelle-joubert-joseph\/\">Joubert, Joseph<\/a><\/li>\n<li class=\"page_item page-item-5350\"><a href=\"https:\/\/dieter-jenz.de\/lc\/zitate-nach-quellen\/zitate-quelle-jung-carl-gustav\/\">Jung, Carl Gustav<\/a><\/li>\n<li class=\"page_item page-item-5347\"><a href=\"https:\/\/dieter-jenz.de\/lc\/zitate-nach-quellen\/zitate-quelle-karl-reinhard\/\">Karl, Reinhard<\/a><\/li>\n<li class=\"page_item page-item-5343\"><a href=\"https:\/\/dieter-jenz.de\/lc\/zitate-nach-quellen\/zitate-quelle-kierkegaard-soeren\/\">Kierkegaard, S\u00f6ren<\/a><\/li>\n<li class=\"page_item page-item-5320\"><a href=\"https:\/\/dieter-jenz.de\/lc\/zitate-nach-quellen\/zitate-quelle-luther-king-jr-martin\/\">King jr, Martin Luther<\/a><\/li>\n<li class=\"page_item page-item-5339\"><a href=\"https:\/\/dieter-jenz.de\/lc\/zitate-nach-quellen\/zitate-quelle-knef-hildegard\/\">Knef, Hildegard<\/a><\/li>\n<li class=\"page_item page-item-7102\"><a href=\"https:\/\/dieter-jenz.de\/lc\/zitate-nach-quellen\/zitate-quelle-kolping-adolph\/\">Kolping, Adolph<\/a><\/li>\n<li class=\"page_item page-item-5335\"><a href=\"https:\/\/dieter-jenz.de\/lc\/zitate-nach-quellen\/zitate-quelle-korczak-janusz\/\">Korczak, Janusz<\/a><\/li>\n<li class=\"page_item page-item-5331\"><a href=\"https:\/\/dieter-jenz.de\/lc\/zitate-nach-quellen\/zitate-quelle-kuebler-ross-elisabeth\/\">K\u00fcbler-Ross, Elisabeth<\/a><\/li>\n<li class=\"page_item page-item-5327\"><a href=\"https:\/\/dieter-jenz.de\/lc\/zitate-nach-quellen\/zitate-quelle-laotse\/\">Laotse<\/a><\/li>\n<li class=\"page_item page-item-5324\"><a href=\"https:\/\/dieter-jenz.de\/lc\/zitate-nach-quellen\/zitate-quelle-luescher-max\/\">L\u00fcscher, Max<\/a><\/li>\n<li class=\"page_item page-item-5315\"><a href=\"https:\/\/dieter-jenz.de\/lc\/zitate-nach-quellen\/zitate-quelle-mandela-nelson\/\">Mandela, Nelson<\/a><\/li>\n<li class=\"page_item page-item-5310\"><a href=\"https:\/\/dieter-jenz.de\/lc\/zitate-nach-quellen\/zitate-quelle-mcdavid-janis\/\">McDavid, Janis<\/a><\/li>\n<li class=\"page_item page-item-5306\"><a href=\"https:\/\/dieter-jenz.de\/lc\/zitate-nach-quellen\/zitate-quelle-meister-eckhart\/\">Meister Eckhart<\/a><\/li>\n<li class=\"page_item page-item-5301\"><a href=\"https:\/\/dieter-jenz.de\/lc\/zitate-nach-quellen\/zitate-quelle-mello-anthony-de\/\">Mello, Anthony de<\/a><\/li>\n<li class=\"page_item page-item-5297\"><a href=\"https:\/\/dieter-jenz.de\/lc\/zitate-nach-quellen\/zitate-quelle-messner-reinhold\/\">Messner, Reinhold<\/a><\/li>\n<li class=\"page_item page-item-5293\"><a href=\"https:\/\/dieter-jenz.de\/lc\/zitate-nach-quellen\/zitate-quelle-monbourquette-jean\/\">Monbourquette, Jean<\/a><\/li>\n<li class=\"page_item page-item-5289\"><a href=\"https:\/\/dieter-jenz.de\/lc\/zitate-nach-quellen\/zitate-quelle-nietzsche-friedrich\/\">Nietzsche, Friedrich<\/a><\/li>\n<li class=\"page_item page-item-5285\"><a href=\"https:\/\/dieter-jenz.de\/lc\/zitate-nach-quellen\/zitate-quelle-pascal-blaise\/\">Pascal, Blaise<\/a><\/li>\n<li class=\"page_item page-item-5280\"><a href=\"https:\/\/dieter-jenz.de\/lc\/zitate-nach-quellen\/zitate-quelle-pavese-cesare\/\">Pavese, Cesare<\/a><\/li>\n<li class=\"page_item page-item-5276\"><a href=\"https:\/\/dieter-jenz.de\/lc\/zitate-nach-quellen\/zitate-quelle-pindar\/\">Pindar<\/a><\/li>\n<li class=\"page_item page-item-5272\"><a href=\"https:\/\/dieter-jenz.de\/lc\/zitate-nach-quellen\/zitate-quelle-poimen\/\">Poimen<\/a><\/li>\n<li class=\"page_item page-item-5268\"><a href=\"https:\/\/dieter-jenz.de\/lc\/zitate-nach-quellen\/zitate-quelle-radtke-guenter\/\">Radtke, G\u00fcnter<\/a><\/li>\n<li class=\"page_item page-item-5264\"><a href=\"https:\/\/dieter-jenz.de\/lc\/zitate-nach-quellen\/zitate-quelle-riesenhuber-heinz\/\">Riesenhuber, Heinz<\/a><\/li>\n<li class=\"page_item page-item-5257\"><a href=\"https:\/\/dieter-jenz.de\/lc\/zitate-nach-quellen\/zitate-quelle-rogers-carl\/\">Rogers, Carl<\/a><\/li>\n<li class=\"page_item page-item-5253\"><a href=\"https:\/\/dieter-jenz.de\/lc\/zitate-nach-quellen\/zitate-quelle-roosevelt-eleanor\/\">Roosevelt, Eleanor<\/a><\/li>\n<li class=\"page_item page-item-5249\"><a href=\"https:\/\/dieter-jenz.de\/lc\/zitate-nach-quellen\/zitate-quelle-rosenberg-marshall\/\">Rosenberg, Marshall<\/a><\/li>\n<li class=\"page_item page-item-5246\"><a href=\"https:\/\/dieter-jenz.de\/lc\/zitate-nach-quellen\/zitate-quelle-rowling-joanne\/\">Rowling, Joanne<\/a><\/li>\n<li class=\"page_item page-item-5228\"><a href=\"https:\/\/dieter-jenz.de\/lc\/zitate-nach-quellen\/zitate-quelle-saint-exupery-antoine-de\/\">Saint-Exupery, Antoine de<\/a><\/li>\n<li class=\"page_item page-item-5224\"><a href=\"https:\/\/dieter-jenz.de\/lc\/zitate-nach-quellen\/zitate-quelle-sales-franz-von\/\">Sales, Franz von<\/a><\/li>\n<li class=\"page_item page-item-5220\"><a href=\"https:\/\/dieter-jenz.de\/lc\/zitate-nach-quellen\/zitate-quelle-sautner-thomas\/\">Sautner, Thomas<\/a><\/li>\n<li class=\"page_item page-item-5216\"><a href=\"https:\/\/dieter-jenz.de\/lc\/zitate-nach-quellen\/zitate-quelle-schaeferling-helga\/\">Sch\u00e4ferling, Helga<\/a><\/li>\n<li class=\"page_item page-item-5212\"><a href=\"https:\/\/dieter-jenz.de\/lc\/zitate-nach-quellen\/zitate-quelle-schweitzer-albert\/\">Schweitzer, Albert<\/a><\/li>\n<li class=\"page_item page-item-5209\"><a href=\"https:\/\/dieter-jenz.de\/lc\/zitate-nach-quellen\/zitate-quelle-seligman-martin\/\">Seligman, Martin<\/a><\/li>\n<li class=\"page_item page-item-6739\"><a href=\"https:\/\/dieter-jenz.de\/lc\/zitate-nach-quellen\/zitate-quelle-seneca\/\">Seneca<\/a><\/li>\n<li class=\"page_item page-item-5205\"><a href=\"https:\/\/dieter-jenz.de\/lc\/zitate-nach-quellen\/zitate-quelle-siena-katharina-von\/\">Siena, Katharina von<\/a><\/li>\n<li class=\"page_item page-item-5717\"><a href=\"https:\/\/dieter-jenz.de\/lc\/zitate-nach-quellen\/zitate-quelle-smedes-lewis\/\">Smedes, Lewis<\/a><\/li>\n<li class=\"page_item page-item-5200\"><a href=\"https:\/\/dieter-jenz.de\/lc\/zitate-nach-quellen\/zitate-quelle-stein-edith\/\">Stein, Edith<\/a><\/li>\n<li class=\"page_item page-item-8851\"><a href=\"https:\/\/dieter-jenz.de\/lc\/zitate-nach-quellen\/zitate-quelle-steindl-rast-david\/\">Steindl-Rast, David<\/a><\/li>\n<li class=\"page_item page-item-5183\"><a href=\"https:\/\/dieter-jenz.de\/lc\/zitate-nach-quellen\/zitate-quelle-strindberg-august\/\">Strindberg, August<\/a><\/li>\n<li class=\"page_item page-item-5181\"><a href=\"https:\/\/dieter-jenz.de\/lc\/zitate-nach-quellen\/zitate-quelle-thatcher-margaret\/\">Thatcher, Margaret<\/a><\/li>\n<li class=\"page_item page-item-5179\"><a href=\"https:\/\/dieter-jenz.de\/lc\/zitate-nach-quellen\/zitate-quelle-voltaire\/\">Voltaire<\/a><\/li>\n<li class=\"page_item page-item-5177\"><a href=\"https:\/\/dieter-jenz.de\/lc\/zitate-nach-quellen\/zitate-quelle-waite-terry\/\">Waite, Terry<\/a><\/li>\n<li class=\"page_item page-item-5175\"><a href=\"https:\/\/dieter-jenz.de\/lc\/zitate-nach-quellen\/zitate-quelle-watzlawik-paul\/\">Watzlawik, Paul<\/a><\/li>\n<li class=\"page_item page-item-5173\"><a href=\"https:\/\/dieter-jenz.de\/lc\/zitate-nach-quellen\/zitate-quelle-weizsaecker-richard-von\/\">Weizs\u00e4cker, Richard von<\/a><\/li>\n<\/ul> <\/div><div class=\"su-expand-link su-expand-link-more\" style=\"text-align:left\"><a href=\"javascript:;\" style=\"color:#0088FF;border-color:#0088FF\"><span style=\"border-color:#0088FF\">Mehr anzeigen<\/span><\/a><\/div><div class=\"su-expand-link su-expand-link-less\" style=\"text-align:left\"><a href=\"javascript:;\" style=\"color:#0088FF;border-color:#0088FF\"><span style=\"border-color:#0088FF\">Weniger anzeigen<\/span><\/a><\/div><\/div><\/div><\/div>\n\n\n<div class=\"su-box su-box-style-default\" id=\"\" style=\"border-color:#000000;border-radius:3px;\"><div class=\"su-box-title\" style=\"background-color:#333333;color:#FFFFFF;border-top-left-radius:1px;border-top-right-radius:1px\">Zitate nach Stichworten <\/div><div class=\"su-box-content su-u-clearfix su-u-trim\" style=\"border-bottom-left-radius:1px;border-bottom-right-radius:1px\"><div class=\"su-expand su-expand-collapsed su-expand-link-style-default\" data-height=\"100\"><div class=\"su-expand-content su-u-trim\" style=\"color:#333333;max-height:100px;overflow:hidden\"><ul class=\"su-subpages\"><li class=\"page_item page-item-3679\"><a href=\"https:\/\/dieter-jenz.de\/lc\/zitate-nach-stichworten\/zitate-begeisterung-begeistert-sein\/\">Begeisterung, begeistert (sein)<\/a><\/li>\n<li class=\"page_item page-item-3746\"><a href=\"https:\/\/dieter-jenz.de\/lc\/zitate-nach-stichworten\/zitate-beziehung-in-beziehung-leben\/\">Beziehung, in Beziehung leben<\/a><\/li>\n<li class=\"page_item page-item-4012\"><a href=\"https:\/\/dieter-jenz.de\/lc\/zitate-nach-stichworten\/zitate-dankbarkeit-dankbar-sein-werden\/\">Dankbarkeit, dankbar sein\/werden<\/a><\/li>\n<li class=\"page_item page-item-3888\"><a href=\"https:\/\/dieter-jenz.de\/lc\/zitate-nach-stichworten\/zitate-depression-deprimiert-sein\/\">Depression, deprimiert sein<\/a><\/li>\n<li class=\"page_item page-item-4039\"><a href=\"https:\/\/dieter-jenz.de\/lc\/zitate-nach-stichworten\/zitate-einstellung-eingestellt-sein\/\">Einstellung, eingestellt sein<\/a><\/li>\n<li class=\"page_item page-item-3709\"><a href=\"https:\/\/dieter-jenz.de\/lc\/zitate-nach-stichworten\/zitate-erfolg-erfolgreich-sein-werden\/\">Erfolg, erfolgreich sein\/werden<\/a><\/li>\n<li class=\"page_item page-item-3735\"><a href=\"https:\/\/dieter-jenz.de\/lc\/zitate-nach-stichworten\/zitate-freiheit-frei-sein-werden\/\">Freiheit, frei sein\/werden<\/a><\/li>\n<li class=\"page_item page-item-3856\"><a href=\"https:\/\/dieter-jenz.de\/lc\/zitate-nach-stichworten\/zitate-freundschaft\/\">Freundschaft<\/a><\/li>\n<li class=\"page_item page-item-3717\"><a href=\"https:\/\/dieter-jenz.de\/lc\/zitate-nach-stichworten\/zitate-glueck-gluecklich-sein-werden\/\">Gl\u00fcck, gl\u00fccklich sein\/werden<\/a><\/li>\n<li class=\"page_item page-item-4052\"><a href=\"https:\/\/dieter-jenz.de\/lc\/zitate-nach-stichworten\/zitate-heilung-heilen-geheilt-werden\/\">Heilung, heilen, geheilt werden<\/a><\/li>\n<li class=\"page_item page-item-3597\"><a href=\"https:\/\/dieter-jenz.de\/lc\/zitate-nach-stichworten\/zitate-hoffnung-hoffen\/\">Hoffnung, hoffen<\/a><\/li>\n<li class=\"page_item page-item-3602\"><a href=\"https:\/\/dieter-jenz.de\/lc\/zitate-nach-stichworten\/zitate-krise\/\">Krise<\/a><\/li>\n<li class=\"page_item page-item-3750\"><a href=\"https:\/\/dieter-jenz.de\/lc\/zitate-nach-stichworten\/zitate-leben-gestalten\/\">Leben gestalten<\/a><\/li>\n<li class=\"page_item page-item-3714\"><a href=\"https:\/\/dieter-jenz.de\/lc\/zitate-nach-stichworten\/zitate-lebensaufgabe\/\">Lebensaufgabe<\/a><\/li>\n<li class=\"page_item page-item-3643\"><a href=\"https:\/\/dieter-jenz.de\/lc\/zitate-nach-stichworten\/zitate-liebe-lieben-geliebt-werden\/\">Liebe, lieben, geliebt werden<\/a><\/li>\n<li class=\"page_item page-item-4009\"><a href=\"https:\/\/dieter-jenz.de\/lc\/zitate-nach-stichworten\/zitate-mut-mutig-sein\/\">Mut, mutig (sein)<\/a><\/li>\n<li class=\"page_item page-item-4164\"><a href=\"https:\/\/dieter-jenz.de\/lc\/zitate-nach-stichworten\/zitate-persoenlichkeitsentwicklung\/\">Pers\u00f6nlichkeitsentwicklung, pers\u00f6nliches Wachstum<\/a><\/li>\n<li class=\"page_item page-item-3742\"><a href=\"https:\/\/dieter-jenz.de\/lc\/zitate-nach-stichworten\/zitate-sinn-lebenssinn\/\">Sinn, Lebenssinn<\/a><\/li>\n<li class=\"page_item page-item-4004\"><a href=\"https:\/\/dieter-jenz.de\/lc\/zitate-nach-stichworten\/zitate-staerke-staerken-stark-sein-werden\/\">St\u00e4rke (seelisch), st\u00e4rken, stark sein\/werden<\/a><\/li>\n<li class=\"page_item page-item-3902\"><a href=\"https:\/\/dieter-jenz.de\/lc\/zitate-nach-stichworten\/zitate-veraenderung-veraendern\/\">Ver\u00e4nderung, (ver)\u00e4ndern<\/a><\/li>\n<li class=\"page_item page-item-3997\"><a href=\"https:\/\/dieter-jenz.de\/lc\/zitate-nach-stichworten\/zitate-vergebung-vergeben-verzeihen\/\">Vergebung, vergeben, verzeihen<\/a><\/li>\n<li class=\"page_item page-item-3975\"><a href=\"https:\/\/dieter-jenz.de\/lc\/zitate-nach-stichworten\/zitate-verletzung-seelisch-verletzt-verletzlich\/\">Verletzung (seelisch), verletzt sein\/werden, verletzlich<\/a><\/li>\n<li class=\"page_item page-item-3723\"><a href=\"https:\/\/dieter-jenz.de\/lc\/zitate-nach-stichworten\/zitate-vertrauen\/\">Vertrauen<\/a><\/li>\n<li class=\"page_item page-item-4034\"><a href=\"https:\/\/dieter-jenz.de\/lc\/zitate-nach-stichworten\/zitate-wertschaetzung-wertschaetzen\/\">Wertsch\u00e4tzung, sich\/jemand\/etwas wertsch\u00e4tzen<\/a><\/li>\n<li class=\"page_item page-item-3731\"><a href=\"https:\/\/dieter-jenz.de\/lc\/zitate-nach-stichworten\/zitate-ziel-ziele\/\">Ziel, Ziele<\/a><\/li>\n<\/ul> <\/div><div class=\"su-expand-link su-expand-link-more\" style=\"text-align:left\"><a href=\"javascript:;\" style=\"color:#0088FF;border-color:#0088FF\"><span style=\"border-color:#0088FF\">Mehr anzeigen<\/span><\/a><\/div><div class=\"su-expand-link su-expand-link-less\" style=\"text-align:left\"><a href=\"javascript:;\" style=\"color:#0088FF;border-color:#0088FF\"><span style=\"border-color:#0088FF\">Weniger anzeigen<\/span><\/a><\/div><\/div><\/div><\/div>\n\n\n\n<div class=\"wp-block-group\"><div class=\"wp-block-group__inner-container is-layout-flow wp-block-group-is-layout-flow\"><div class=\"su-box su-box-style-default\" id=\"\" style=\"border-color:#000000;border-radius:3px;\"><div class=\"su-box-title\" style=\"background-color:#333333;color:#FFFFFF;border-top-left-radius:1px;border-top-right-radius:1px\">Zitate-Suche *<\/div><div class=\"su-box-content su-u-clearfix su-u-trim\" style=\"border-bottom-left-radius:1px;border-bottom-right-radius:1px\"><form data-min-no-for-search=2 data-result-box-max-height=400 data-form-id=4451 class=\"is-search-form is-form-style is-form-style-3 is-form-id-4451 is-ajax-search\" action=\"https:\/\/dieter-jenz.de\/lc\/\" method=\"get\" role=\"search\" ><label for=\"is-search-input-4451\"><span class=\"is-screen-reader-text\">Search for:<\/span><input  type=\"search\" id=\"is-search-input-4451\" name=\"s\" value=\"\" class=\"is-search-input\" placeholder=\"Suchbegriff ...\" autocomplete=off \/><span class=\"is-loader-image\" style=\"display: none;background-image:url(https:\/\/dieter-jenz.de\/lc\/wp-content\/plugins\/add-search-to-menu\/public\/images\/spinner.gif);\" ><\/span><\/label><button type=\"submit\" class=\"is-search-submit\"><span class=\"is-screen-reader-text\">Search Button<\/span><span class=\"is-search-icon\"><svg focusable=\"false\" aria-label=\"Search\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 24 24\" width=\"24px\"><path d=\"M15.5 14h-.79l-.28-.27C15.41 12.59 16 11.11 16 9.5 16 5.91 13.09 3 9.5 3S3 5.91 3 9.5 5.91 16 9.5 16c1.61 0 3.09-.59 4.23-1.57l.27.28v.79l5 4.99L20.49 19l-4.99-5zm-6 0C7.01 14 5 11.99 5 9.5S7.01 5 9.5 5 14 7.01 14 9.5 11.99 14 9.5 14z\"><\/path><\/svg><\/span><\/button><input type=\"hidden\" name=\"id\" value=\"4451\" \/><input type=\"hidden\" name=\"post_type\" value=\"post\" \/><\/form><\/div><\/div>\n\n\n\n<p class=\"has-small-font-size\">* Sie k\u00f6nnen nach Text suchen, der in Zitaten vorkommt (Beispiele: &#8222;Gl\u00fcck&#8220;, &#8222;hoff&#8220;)<\/p>\n<\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>\u201eFreundschaft w\u00e4hrt am l\u00e4ngsten, wenn sie mit dem gegenseitigen Versprechen, sich immer die Wahrheit zu sagen, besiegelt wird.\u201c Ralph Waldo Emerson<\/p>\n","protected":false},"author":2,"featured_media":4081,"comment_status":"closed","ping_status":"open","sticky":false,"template":"template-full-width-only-content.php","format":"standard","meta":{"footnotes":""},"categories":[90,64,68],"tags":[111,65],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Freundschaft w\u00e4hrt am l\u00e4ngsten, wenn sie mit ... besiegelt wird<\/title>\n<meta name=\"description\" content=\"Freundschaft w\u00e4hrt am l\u00e4ngsten, wenn sie mit dem gegenseitigen Versprechen, sich immer die Wahrheit zu sagen, besiegelt wird.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dieter-jenz.de\/lc\/freundschaft-waehrt-am-laengsten-wenn-sie-mit-dem-versprechen-besiegelt-wird-emerson\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Freundschaft w\u00e4hrt am l\u00e4ngsten, wenn sie mit ... besiegelt wird\" \/>\n<meta property=\"og:description\" content=\"Freundschaft w\u00e4hrt am l\u00e4ngsten, wenn sie mit dem gegenseitigen Versprechen, sich immer die Wahrheit zu sagen, besiegelt wird.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dieter-jenz.de\/lc\/freundschaft-waehrt-am-laengsten-wenn-sie-mit-dem-versprechen-besiegelt-wird-emerson\/\" \/>\n<meta property=\"og:site_name\" content=\"Dieter Jenz, Begleitung und Coaching\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/dieter.jenz.inspiration\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/dieter.jenz.inspiration\" \/>\n<meta property=\"article:published_time\" content=\"2020-08-11T06:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-01-31T08:32:30+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dieter-jenz.de\/lc\/wp-content\/uploads\/2020\/08\/Freundschaft-w\u00e4hrt-am-l\u00e4ngsten-R.W.-Emerson.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"735\" \/>\n\t<meta property=\"og:image:height\" content=\"1102\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Dieter Jenz\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/dieterjenz\" \/>\n<meta name=\"twitter:site\" content=\"@dieterjenz\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Dieter Jenz\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"5\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/dieter-jenz.de\/lc\/freundschaft-waehrt-am-laengsten-wenn-sie-mit-dem-versprechen-besiegelt-wird-emerson\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/dieter-jenz.de\/lc\/freundschaft-waehrt-am-laengsten-wenn-sie-mit-dem-versprechen-besiegelt-wird-emerson\/\"},\"author\":{\"name\":\"Dieter Jenz\",\"@id\":\"https:\/\/dieter-jenz.de\/lc\/#\/schema\/person\/618cfd5c289d0a23930cb258a43679ab\"},\"headline\":\"Freundschaft w\u00e4hrt am l\u00e4ngsten, wenn sie mit &#8230; besiegelt wird\",\"datePublished\":\"2020-08-11T06:00:00+00:00\",\"dateModified\":\"2024-01-31T08:32:30+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/dieter-jenz.de\/lc\/freundschaft-waehrt-am-laengsten-wenn-sie-mit-dem-versprechen-besiegelt-wird-emerson\/\"},\"wordCount\":632,\"publisher\":{\"@id\":\"https:\/\/dieter-jenz.de\/lc\/#\/schema\/person\/618cfd5c289d0a23930cb258a43679ab\"},\"image\":{\"@id\":\"https:\/\/dieter-jenz.de\/lc\/freundschaft-waehrt-am-laengsten-wenn-sie-mit-dem-versprechen-besiegelt-wird-emerson\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dieter-jenz.de\/lc\/wp-content\/uploads\/2020\/08\/Freundschaft-w\u00e4hrt-am-l\u00e4ngsten-R.W.-Emerson.jpeg\",\"keywords\":[\"Freundschaft\",\"Inspiration\"],\"articleSection\":[\"Emerson, Ralph Waldo\",\"Ermutigung und Inspiration\",\"Zitate\"],\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/dieter-jenz.de\/lc\/freundschaft-waehrt-am-laengsten-wenn-sie-mit-dem-versprechen-besiegelt-wird-emerson\/\",\"url\":\"https:\/\/dieter-jenz.de\/lc\/freundschaft-waehrt-am-laengsten-wenn-sie-mit-dem-versprechen-besiegelt-wird-emerson\/\",\"name\":\"Freundschaft w\u00e4hrt am l\u00e4ngsten, wenn sie mit ... besiegelt wird\",\"isPartOf\":{\"@id\":\"https:\/\/dieter-jenz.de\/lc\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/dieter-jenz.de\/lc\/freundschaft-waehrt-am-laengsten-wenn-sie-mit-dem-versprechen-besiegelt-wird-emerson\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/dieter-jenz.de\/lc\/freundschaft-waehrt-am-laengsten-wenn-sie-mit-dem-versprechen-besiegelt-wird-emerson\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dieter-jenz.de\/lc\/wp-content\/uploads\/2020\/08\/Freundschaft-w\u00e4hrt-am-l\u00e4ngsten-R.W.-Emerson.jpeg\",\"datePublished\":\"2020-08-11T06:00:00+00:00\",\"dateModified\":\"2024-01-31T08:32:30+00:00\",\"description\":\"Freundschaft w\u00e4hrt am l\u00e4ngsten, wenn sie mit dem gegenseitigen Versprechen, sich immer die Wahrheit zu sagen, besiegelt wird.\",\"breadcrumb\":{\"@id\":\"https:\/\/dieter-jenz.de\/lc\/freundschaft-waehrt-am-laengsten-wenn-sie-mit-dem-versprechen-besiegelt-wird-emerson\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/dieter-jenz.de\/lc\/freundschaft-waehrt-am-laengsten-wenn-sie-mit-dem-versprechen-besiegelt-wird-emerson\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/dieter-jenz.de\/lc\/freundschaft-waehrt-am-laengsten-wenn-sie-mit-dem-versprechen-besiegelt-wird-emerson\/#primaryimage\",\"url\":\"https:\/\/dieter-jenz.de\/lc\/wp-content\/uploads\/2020\/08\/Freundschaft-w\u00e4hrt-am-l\u00e4ngsten-R.W.-Emerson.jpeg\",\"contentUrl\":\"https:\/\/dieter-jenz.de\/lc\/wp-content\/uploads\/2020\/08\/Freundschaft-w\u00e4hrt-am-l\u00e4ngsten-R.W.-Emerson.jpeg\",\"width\":735,\"height\":1102,\"caption\":\"Freundschaft w\u00e4hrt am l\u00e4ngsten, R.W. Emerson - Gestaltung: privat\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/dieter-jenz.de\/lc\/freundschaft-waehrt-am-laengsten-wenn-sie-mit-dem-versprechen-besiegelt-wird-emerson\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/dieter-jenz.de\/lc\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Ermutigung und Inspiration\",\"item\":\"https:\/\/dieter-jenz.de\/lc\/category\/ermutigung-und-inspiration\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Freundschaft w\u00e4hrt am l\u00e4ngsten, wenn sie mit &#8230; besiegelt wird\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/dieter-jenz.de\/lc\/#website\",\"url\":\"https:\/\/dieter-jenz.de\/lc\/\",\"name\":\"Dieter Jenz, Begleitung und Coaching\",\"description\":\"Die andere, neue Sichtweise entdecken - auftanken - neue Wege gehen\",\"publisher\":{\"@id\":\"https:\/\/dieter-jenz.de\/lc\/#\/schema\/person\/618cfd5c289d0a23930cb258a43679ab\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/dieter-jenz.de\/lc\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\/\/dieter-jenz.de\/lc\/#\/schema\/person\/618cfd5c289d0a23930cb258a43679ab\",\"name\":\"Dieter Jenz\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/dieter-jenz.de\/lc\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/dieter-jenz.de\/lc\/wp-content\/uploads\/2020\/01\/Logo-Coaching-und-Begleitung.png\",\"contentUrl\":\"https:\/\/dieter-jenz.de\/lc\/wp-content\/uploads\/2020\/01\/Logo-Coaching-und-Begleitung.png\",\"width\":320,\"height\":240,\"caption\":\"Dieter Jenz\"},\"logo\":{\"@id\":\"https:\/\/dieter-jenz.de\/lc\/#\/schema\/person\/image\/\"},\"description\":\"Ich bin Dieter Jenz, Begleiter, Berater und Coach mit Leidenschaft. \u00dcber viele Jahre hinweg habe ich einen reichen Schatz an Kompetenz und Erfahrung erworben. Meine Themen sind die \\\"4L\\\": Lebensaufgabe, Lebensplanung, Lebensnavigation und Lebensqualit\u00e4t.\",\"sameAs\":[\"https:\/\/www.facebook.com\/dieter.jenz.inspiration\",\"https:\/\/www.pinterest.de\/dieterjenz\/\",\"https:\/\/x.com\/https:\/\/twitter.com\/dieterjenz\"],\"url\":\"https:\/\/dieter-jenz.de\/lc\/author\/dieter\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Freundschaft w\u00e4hrt am l\u00e4ngsten, wenn sie mit ... besiegelt wird","description":"Freundschaft w\u00e4hrt am l\u00e4ngsten, wenn sie mit dem gegenseitigen Versprechen, sich immer die Wahrheit zu sagen, besiegelt wird.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dieter-jenz.de\/lc\/freundschaft-waehrt-am-laengsten-wenn-sie-mit-dem-versprechen-besiegelt-wird-emerson\/","og_locale":"de_DE","og_type":"article","og_title":"Freundschaft w\u00e4hrt am l\u00e4ngsten, wenn sie mit ... besiegelt wird","og_description":"Freundschaft w\u00e4hrt am l\u00e4ngsten, wenn sie mit dem gegenseitigen Versprechen, sich immer die Wahrheit zu sagen, besiegelt wird.","og_url":"https:\/\/dieter-jenz.de\/lc\/freundschaft-waehrt-am-laengsten-wenn-sie-mit-dem-versprechen-besiegelt-wird-emerson\/","og_site_name":"Dieter Jenz, Begleitung und Coaching","article_publisher":"https:\/\/www.facebook.com\/dieter.jenz.inspiration","article_author":"https:\/\/www.facebook.com\/dieter.jenz.inspiration","article_published_time":"2020-08-11T06:00:00+00:00","article_modified_time":"2024-01-31T08:32:30+00:00","og_image":[{"width":735,"height":1102,"url":"https:\/\/dieter-jenz.de\/lc\/wp-content\/uploads\/2020\/08\/Freundschaft-w\u00e4hrt-am-l\u00e4ngsten-R.W.-Emerson.jpeg","type":"image\/jpeg"}],"author":"Dieter Jenz","twitter_card":"summary_large_image","twitter_creator":"@https:\/\/twitter.com\/dieterjenz","twitter_site":"@dieterjenz","twitter_misc":{"Verfasst von":"Dieter Jenz","Gesch\u00e4tzte Lesezeit":"5\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/dieter-jenz.de\/lc\/freundschaft-waehrt-am-laengsten-wenn-sie-mit-dem-versprechen-besiegelt-wird-emerson\/#article","isPartOf":{"@id":"https:\/\/dieter-jenz.de\/lc\/freundschaft-waehrt-am-laengsten-wenn-sie-mit-dem-versprechen-besiegelt-wird-emerson\/"},"author":{"name":"Dieter Jenz","@id":"https:\/\/dieter-jenz.de\/lc\/#\/schema\/person\/618cfd5c289d0a23930cb258a43679ab"},"headline":"Freundschaft w\u00e4hrt am l\u00e4ngsten, wenn sie mit &#8230; besiegelt wird","datePublished":"2020-08-11T06:00:00+00:00","dateModified":"2024-01-31T08:32:30+00:00","mainEntityOfPage":{"@id":"https:\/\/dieter-jenz.de\/lc\/freundschaft-waehrt-am-laengsten-wenn-sie-mit-dem-versprechen-besiegelt-wird-emerson\/"},"wordCount":632,"publisher":{"@id":"https:\/\/dieter-jenz.de\/lc\/#\/schema\/person\/618cfd5c289d0a23930cb258a43679ab"},"image":{"@id":"https:\/\/dieter-jenz.de\/lc\/freundschaft-waehrt-am-laengsten-wenn-sie-mit-dem-versprechen-besiegelt-wird-emerson\/#primaryimage"},"thumbnailUrl":"https:\/\/dieter-jenz.de\/lc\/wp-content\/uploads\/2020\/08\/Freundschaft-w\u00e4hrt-am-l\u00e4ngsten-R.W.-Emerson.jpeg","keywords":["Freundschaft","Inspiration"],"articleSection":["Emerson, Ralph Waldo","Ermutigung und Inspiration","Zitate"],"inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/dieter-jenz.de\/lc\/freundschaft-waehrt-am-laengsten-wenn-sie-mit-dem-versprechen-besiegelt-wird-emerson\/","url":"https:\/\/dieter-jenz.de\/lc\/freundschaft-waehrt-am-laengsten-wenn-sie-mit-dem-versprechen-besiegelt-wird-emerson\/","name":"Freundschaft w\u00e4hrt am l\u00e4ngsten, wenn sie mit ... besiegelt wird","isPartOf":{"@id":"https:\/\/dieter-jenz.de\/lc\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dieter-jenz.de\/lc\/freundschaft-waehrt-am-laengsten-wenn-sie-mit-dem-versprechen-besiegelt-wird-emerson\/#primaryimage"},"image":{"@id":"https:\/\/dieter-jenz.de\/lc\/freundschaft-waehrt-am-laengsten-wenn-sie-mit-dem-versprechen-besiegelt-wird-emerson\/#primaryimage"},"thumbnailUrl":"https:\/\/dieter-jenz.de\/lc\/wp-content\/uploads\/2020\/08\/Freundschaft-w\u00e4hrt-am-l\u00e4ngsten-R.W.-Emerson.jpeg","datePublished":"2020-08-11T06:00:00+00:00","dateModified":"2024-01-31T08:32:30+00:00","description":"Freundschaft w\u00e4hrt am l\u00e4ngsten, wenn sie mit dem gegenseitigen Versprechen, sich immer die Wahrheit zu sagen, besiegelt wird.","breadcrumb":{"@id":"https:\/\/dieter-jenz.de\/lc\/freundschaft-waehrt-am-laengsten-wenn-sie-mit-dem-versprechen-besiegelt-wird-emerson\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dieter-jenz.de\/lc\/freundschaft-waehrt-am-laengsten-wenn-sie-mit-dem-versprechen-besiegelt-wird-emerson\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/dieter-jenz.de\/lc\/freundschaft-waehrt-am-laengsten-wenn-sie-mit-dem-versprechen-besiegelt-wird-emerson\/#primaryimage","url":"https:\/\/dieter-jenz.de\/lc\/wp-content\/uploads\/2020\/08\/Freundschaft-w\u00e4hrt-am-l\u00e4ngsten-R.W.-Emerson.jpeg","contentUrl":"https:\/\/dieter-jenz.de\/lc\/wp-content\/uploads\/2020\/08\/Freundschaft-w\u00e4hrt-am-l\u00e4ngsten-R.W.-Emerson.jpeg","width":735,"height":1102,"caption":"Freundschaft w\u00e4hrt am l\u00e4ngsten, R.W. Emerson - Gestaltung: privat"},{"@type":"BreadcrumbList","@id":"https:\/\/dieter-jenz.de\/lc\/freundschaft-waehrt-am-laengsten-wenn-sie-mit-dem-versprechen-besiegelt-wird-emerson\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/dieter-jenz.de\/lc\/"},{"@type":"ListItem","position":2,"name":"Ermutigung und Inspiration","item":"https:\/\/dieter-jenz.de\/lc\/category\/ermutigung-und-inspiration\/"},{"@type":"ListItem","position":3,"name":"Freundschaft w\u00e4hrt am l\u00e4ngsten, wenn sie mit &#8230; besiegelt wird"}]},{"@type":"WebSite","@id":"https:\/\/dieter-jenz.de\/lc\/#website","url":"https:\/\/dieter-jenz.de\/lc\/","name":"Dieter Jenz, Begleitung und Coaching","description":"Die andere, neue Sichtweise entdecken - auftanken - neue Wege gehen","publisher":{"@id":"https:\/\/dieter-jenz.de\/lc\/#\/schema\/person\/618cfd5c289d0a23930cb258a43679ab"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dieter-jenz.de\/lc\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":["Person","Organization"],"@id":"https:\/\/dieter-jenz.de\/lc\/#\/schema\/person\/618cfd5c289d0a23930cb258a43679ab","name":"Dieter Jenz","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/dieter-jenz.de\/lc\/#\/schema\/person\/image\/","url":"https:\/\/dieter-jenz.de\/lc\/wp-content\/uploads\/2020\/01\/Logo-Coaching-und-Begleitung.png","contentUrl":"https:\/\/dieter-jenz.de\/lc\/wp-content\/uploads\/2020\/01\/Logo-Coaching-und-Begleitung.png","width":320,"height":240,"caption":"Dieter Jenz"},"logo":{"@id":"https:\/\/dieter-jenz.de\/lc\/#\/schema\/person\/image\/"},"description":"Ich bin Dieter Jenz, Begleiter, Berater und Coach mit Leidenschaft. \u00dcber viele Jahre hinweg habe ich einen reichen Schatz an Kompetenz und Erfahrung erworben. Meine Themen sind die \"4L\": Lebensaufgabe, Lebensplanung, Lebensnavigation und Lebensqualit\u00e4t.","sameAs":["https:\/\/www.facebook.com\/dieter.jenz.inspiration","https:\/\/www.pinterest.de\/dieterjenz\/","https:\/\/x.com\/https:\/\/twitter.com\/dieterjenz"],"url":"https:\/\/dieter-jenz.de\/lc\/author\/dieter\/"}]}},"_links":{"self":[{"href":"https:\/\/dieter-jenz.de\/lc\/wp-json\/wp\/v2\/posts\/4082"}],"collection":[{"href":"https:\/\/dieter-jenz.de\/lc\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dieter-jenz.de\/lc\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dieter-jenz.de\/lc\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/dieter-jenz.de\/lc\/wp-json\/wp\/v2\/comments?post=4082"}],"version-history":[{"count":5,"href":"https:\/\/dieter-jenz.de\/lc\/wp-json\/wp\/v2\/posts\/4082\/revisions"}],"predecessor-version":[{"id":10995,"href":"https:\/\/dieter-jenz.de\/lc\/wp-json\/wp\/v2\/posts\/4082\/revisions\/10995"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dieter-jenz.de\/lc\/wp-json\/wp\/v2\/media\/4081"}],"wp:attachment":[{"href":"https:\/\/dieter-jenz.de\/lc\/wp-json\/wp\/v2\/media?parent=4082"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dieter-jenz.de\/lc\/wp-json\/wp\/v2\/categories?post=4082"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dieter-jenz.de\/lc\/wp-json\/wp\/v2\/tags?post=4082"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}